{"id":5328,"date":"2023-07-13T13:34:20","date_gmt":"2023-07-13T17:34:20","guid":{"rendered":"https:\/\/dev.nsira-ossnr.gc.ca\/?page_id=5328"},"modified":"2024-04-24T13:58:18","modified_gmt":"2024-04-24T17:58:18","slug":"terms-and-conditions","status":"publish","type":"page","link":"https:\/\/nsira-ossnr.gc.ca\/fr\/avis\/","title":{"rendered":"Avis"},"content":{"rendered":"<section id=\"gm0eaad8e\" class=\"wp-block-gutentor-m4 section-gm0eaad8e gutentor-module gutentor-advanced-columns has-color-bg has-custom-bg\"><div class=\"grid-container\"><div class=\"grid-row\">\n<div id=\"col-gme9c3b7\" class=\"wp-block-gutentor-m4-col col-gme9c3b7 gutentor-single-column  grid-lg-12 grid-md-12 grid-12\"><div id=\"section-gme9c3b7\" class=\"section-gme9c3b7 gutentor-col-wrap\">\n<h2 class=\"wp-block-heading\">Avis<\/h2>\n\n\n\n<hr style=\"width: 50px;    color: #cf2e2e;    background-color: #cf2e2e;    height: 3px;    text-align: left;margin-left:0;\" class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\">\n\n\n\n<h3 class=\"wp-block-heading\">Droits d\u2019auteur et de reproduction de contenu<\/h3>\n\n\n\n<p>Le contenu figurant sur ce site Web a \u00e9t\u00e9 con\u00e7u et\/ou rassembl\u00e9 pour offrir aux Canadiens et aux Canadiennes un acc\u00e8s direct aux renseignements concernant l\u2019Office de surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement (OSSNR).<\/p>\n\n\n\n<p class=\"translation-block\">Le contenu de ce site est vis\u00e9 par les dispositions de la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-42\/\">Loi sur le droit d\u2019auteur<\/a>, par les autres lois, les politiques et les r\u00e8glements canadiens pertinents ainsi que par des ententes internationales. Les dispositions de ces instruments permettent d\u2019\u00e9tablir la source d\u2019information et, dans certains cas, d\u2019interdire la reproduction des \u00e9l\u00e9ments de contenu en question sans permission \u00e9crite.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reproduction \u00e0 des fins non commerciales<\/h3>\n\n\n\n<p>L\u2019information figurant sur ce site Web a \u00e9t\u00e9 publi\u00e9e de mani\u00e8re \u00e0 en faciliter l\u2019acc\u00e8s \u00e0 des fins personnelles ou non commerciales. \u00c0 moins d\u2019indication contraire, les utilisateurs peuvent reproduire ces \u00e9l\u00e9ments de contenu, en totalit\u00e9 ou en partie, \u00e0 des fins non commerciales et dans n\u2019importe quel format, sans frais ni autorisation suppl\u00e9mentaire, \u00e0 condition que ces utilisateurs :<\/p>\n\n\n\n<ul>\n<li>fasse preuve de diligence raisonnable en veillant \u00e0 l\u2019exactitude du contenu reproduit;<\/li>\n\n\n\n<li>indiquent le titre complet du contenu reproduit et l\u2019organisation qui en est l\u2019auteur;<\/li>\n\n\n\n<li>indiquent que la reproduction est une copie d\u2019un \u00e9l\u00e9ment de contenu officiel publi\u00e9 par l\u2019OSSNR, fournissent l\u2019adresse URL permettant d\u2019acc\u00e9der \u00e0 cet \u00e9l\u00e9ment de contenu et pr\u00e9cisent que la reproduction n\u2019a pas \u00e9t\u00e9 faite en association avec l\u2019OSSNR ni avec l\u2019appui de celui-ci.<\/li>\n<\/ul>\n\n\n\n<p><strong>\u00c0 moins d\u2019indication contraire, cette autorisation s\u2019applique \u00e9galement \u00e0 toute autre information publi\u00e9e, peu importe le format.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avis sur les serveurs tiers<\/h3>\n\n\n\n<p>Pour am\u00e9liorer la fonctionnalit\u00e9 du site Web de l\u2019OSSNR, certains fichiers (tels que des biblioth\u00e8ques de source ouverte, des images et des scripts) peuvent \u00eatre achemin\u00e9s automatiquement \u00e0 votre navigateur par l\u2019interm\u00e9diaire d\u2019un serveur tiers ou d\u2019un r\u00e9seau de diffusion de contenu de confiance. L\u2019acheminement de ces fichiers a pour but de fournir une exp\u00e9rience d\u2019utilisateur sans heurt en acc\u00e9l\u00e9rant les temps de r\u00e9ponse et en \u00e9vitant \u00e0 chaque visiteur de devoir t\u00e9l\u00e9charger ces fichiers. L\u00e0 o\u00f9 il y a lieu, des d\u00e9clarations de confidentialit\u00e9 propres \u00e0 ces fichiers sont incluses dans notre avis de confidentialit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Marques et reproduction de symboles<\/h3>\n\n\n\n<p class=\"translation-block\">Les symboles officiels du gouvernement du Canada, y compris le mot-symbole \u00ab Canada \u00bb, le symbole du drapeau et la signature de l\u2019OSSNR comprenant les armoiries du Canada, ne peuvent \u00eatre reproduits, que ce soit \u00e0 des fins commerciales ou non commerciales, sans <a href=\"https:\/\/www.canada.ca\/fr\/secretariat-conseil-tresor\/sujets\/communications-gouvernementales\/exigences-image-marque\/protection-juridique-symboles-officiels-gouvernement-canada.html\">autorisation \u00e9crite<\/a> pr\u00e9alable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reproduction \u00e0 des fins commerciales<\/h3>\n\n\n\n<p>\u00c0 moins d\u2019indication contraire, il est interdit de reproduire le contenu de ce site, en totalit\u00e9 ou en partie, pour diffusion \u00e0 des fins commerciales sans l\u2019autorisation \u00e9crite pr\u00e9alable de l\u2019OSSNR, au nom du gouvernement du Canada, le titulaire du droit d\u2019auteur.<\/p>\n\n\n\n<p class=\"translation-block\">Pour obtenir l\u2019autorisation de reproduire \u00e0 des fins commerciales des \u00e9l\u00e9ments de contenu du gouvernement du Canada figurant sur ce site, veuillez communiquer avec nous et demander l\u2019affranchissement du droit d\u2019auteur de la Couronne, et ce, <a href=\"mailto:MEDIA-MEDIAS@nsira-ossnr.gc.ca\">par courriel<\/a> ou par la poste \u00e0 l\u2019adresse suivante :<\/p>\n\n\n\n<p>Office de surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement<br>Attention: NSIRA Communications<br>C.P. 2430, succursale D<br>Ottawa (Ontario)<br>K1P 5W5 Canada<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00c9l\u00e9ments de contenu de tiers<\/h3>\n\n\n\n<p class=\"translation-block\">Certains \u00e9l\u00e9ments de contenu et \u00e9l\u00e9ments graphiques figurant sur ce site Web peuvent \u00eatre vis\u00e9s par des droits d\u2019auteur d\u00e9tenus par d\u2019autres organisations. Dans de tels cas, certaines restrictions quant \u00e0 la reproduction d\u2019\u00e9l\u00e9ments de contenu ou d\u2019\u00e9l\u00e9ments graphiques peuvent s\u2019appliquer et il peut \u00eatre n\u00e9cessaire de demander l\u2019autorisation du titulaire des droits avant de reproduire ces \u00e9l\u00e9ments. Pour de plus amples renseignements sur les droits d\u2019auteur concernant les \u00e9l\u00e9ments de contenu de tiers, veuillez <a href=\"mailto:MEDIA-MEDIAS@nsira-ossnr.gc.ca\">communiquer avec nous<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avis concernant les hyperliens<\/h3>\n\n\n\n<p>Ce site Web contient des liens vers des sites de tiers. L\u2019OSSNR fournit ces liens uniquement par courtoisie \u00e0 l\u2019endroit de ses visiteurs. Nous n\u2019assumons aucune responsabilit\u00e9 \u00e0 l\u2019\u00e9gard du contenu des sites de tiers et ne garantissons pas qu\u2019il est exact, \u00e0 jour ou fiable. De m\u00eame, un lien fourni vers un tel site ne signifie en aucun cas que nous approuvons ou recommandons les produits, les services ou les renseignements qui s\u2019y trouvent.<\/p>\n\n\n\n<p class=\"translation-block\">Les sites Web ne relevant pas du gouvernement du Canada ne sont pas vis\u00e9s par la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/p-21\/index.html\">Loi sur la protection des renseignements personnels<\/a> ni par la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/o-3.01\/\">Loi sur les langues officielles<\/a>, et peuvent ne pas \u00eatre accessibles aux personnes handicap\u00e9es ou ne pas \u00eatre aussi s\u00fbrs que le pr\u00e9sent site. L\u2019information figurant sur ces sites de tiers pourrait n\u2019\u00eatre offerte que dans la ou les langues qui y sont employ\u00e9es. En ce qui concerne la protection des renseignements personnels, il est recommand\u00e9 aux visiteurs de consulter les politiques de ces sites \u00e0 cet \u00e9gard avant de fournir des renseignements personnels.<\/p>\n\n\n\n<p>L\u2019OSSNR se d\u00e9gage de toute responsabilit\u00e9 en ce qui concerne votre acc\u00e8s aux sites Web de tiers auxquels les hyperliens conduisent. Lorsque vous suivez, sur le site Web de l\u2019OSSNR, des hyperliens vous amenant vers des sites Web externes, vous le faites \u00e0 vos propres risques.<\/p>\n\n\n\n<p>L\u2019OSSNR se r\u00e9serve le droit d\u2019examiner et de r\u00e9\u00e9valuer r\u00e9guli\u00e8rement tous les liens ainsi que de supprimer tout lien sans avis pr\u00e9alable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avis concernant les langues officielles<\/h3>\n\n\n\n<p class=\"translation-block\">La <em>Loi sur les langues officielles<\/em>, le <em>R\u00e8glement sur les langues officielles \u2013 communications avec le public et prestation des services<\/em> et les exigences des politiques du Conseil du Tr\u00e9sor \u00e9tablissent dans quels contextes nous devons employer le fran\u00e7ais et l\u2019anglais pour fournir des services aux membres du public ou pour communiquer avec eux.\u00a0<\/p>\n\n\n\n<p class=\"translation-block\">L\u2019OSSNR s\u2019engage \u00e0 voir \u00e0 ce que tous les \u00e9l\u00e9ments de contenu figurant sur ce site et \u00e0 ce que ceux qu\u2019elle diffuse sur les <a href=\"https:\/\/twitter.com\/nsiracanada?lang=en\">m\u00e9dias sociaux<\/a> soient pr\u00e9sent\u00e9s simultan\u00e9ment en fran\u00e7ais et en anglais, et \u00e0 ce que les deux versions soient de qualit\u00e9 \u00e9gale.<\/p>\n\n\n\n<p class=\"translation-block\">Toutefois, les utilisateurs doivent savoir que certains renseignements provenant de sources externes sont fournis par courtoisie et ne sont pr\u00e9sent\u00e9s que dans la langue dans laquelle ils ont \u00e9t\u00e9 fournis. Certains hyperliens dirigent les utilisateurs vers des sites Web d\u2019organisations ou d\u2019autres entit\u00e9s qui ne sont pas assujetties \u00e0 la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/o-3.01\/\">Loi sur les langues officielles<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/nsira-ossnr.gc.ca\/fr\/politique-de-confidentialite\/\">Avis de confidentialit\u00e9<\/a><\/h3>\n\n\n\n<p class=\"translation-block\">Les informations personnelles recueillies par la NSIRA sont prot\u00e9g\u00e9es par <em>La Loi sur la protection de la vie priv\u00e9e<\/em>. Pour de plus amples informations sur les pratiques de l'ARILE en mati\u00e8re de protection de la vie priv\u00e9e, veuillez consulter la d\u00e9claration g\u00e9n\u00e9rale de confidentialit\u00e9 de l'Agence. Pour de plus amples informations sur les pratiques de l'ARILE en mati\u00e8re de protection de la vie priv\u00e9e concernant un site web de l'ARILE, veuillez consulter <a href=\"\/fr\/politique-de-confidentialite\/\">l'avis de confidentialit\u00e9 du site web<\/a> de l'Agence.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avis sur l\u2019accessibilit\u00e9<\/h3>\n\n\n\n<p class=\"translation-block\">L\u2019OSSNR s\u2019engage \u00e0 garantir un acc\u00e8s \u00e9quitable \u00e0 l\u2019information, quelles que soient les technologies utilis\u00e9es. Nous nous effor\u00e7ons en permanence de rendre notre site accessible \u00e0 tous, y compris aux personnes handicap\u00e9es et \u00e0 celles qui utilisent des appareils fonctionnels. Pour signaler un obstacle rencontr\u00e9 lors de la navigation sur notre site Web ou pour obtenir des renseignements figurant sur notre site Web dans un autre format, veuillez <a href=\"mailto:MEDIA-MEDIAS@nsira-ossnr.gc.ca\">communiquer avec nous<\/a>.<\/p>\n\n\n\n<p>Les utilisateurs doivent savoir que les plateformes de m\u00e9dias sociaux sont des fournisseurs de services tiers et ne sont donc pas tenues de respecter les normes du gouvernement du Canada en mati\u00e8re d\u2019accessibilit\u00e9 du Web, et que les sites Web de tiers auxquels les utilisateurs acc\u00e8dent au moyen de liens fournis par courtoisie peuvent \u00e9galement ne pas \u00eatre assujettis \u00e0 ces normes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Avis sur les m\u00e9dias sociaux<\/h3>\n\n\n\n<p>Cet avis explique comment l\u2019OSSNR interagit avec le public sur les plateformes de m\u00e9dias sociaux.<\/p>\n\n\n\n<p>Votre interaction sur les m\u00e9dias sociaux avec l\u2019OSSNR sur les m\u00e9dias sociaux est r\u00e9gie en partie par les conditions de service ou les modalit\u00e9s d\u2019utilisation des fournisseurs tiers de plateformes de m\u00e9dias sociaux concern\u00e9s, ainsi que par les modalit\u00e9s suivantes. Le gouvernement du Canada n\u2019a aucun contr\u00f4le sur les conditions de service et les modalit\u00e9s d\u2019utilisation des fournisseurs de plateformes de m\u00e9dias sociaux, mais vous \u00eates vivement invit\u00e9 \u00e0 en prendre connaissance, en plus de celles qui suivent.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Contenu et fr\u00e9quence<\/h4>\n\n\n\n<p>L\u2019OSSNR utilise ses comptes de m\u00e9dias sociaux comme m\u00e9thode de rechange pour interagir avec les Canadiens et Canadiennes, pour partager du contenu publi\u00e9 sur son site Web, pour faciliter l\u2019acc\u00e8s \u00e0 ses renseignements et services, et pour donner aux intervenants l\u2019occasion d\u2019interagir dans un environnement informatif et respectueux.<\/p>\n\n\n\n<p>Les plateformes de m\u00e9dias sociaux et leurs serveurs informatiques \u00e9tant g\u00e9r\u00e9s par un tiers, les comptes de m\u00e9dias sociaux sont sujets \u00e0 des pannes qui peuvent \u00e9chapper au contr\u00f4le du gouvernement du Canada. Le gouvernement du Canada se d\u00e9gage de toute responsabilit\u00e9 en cas d\u2019absence de r\u00e9ponse ou d\u2019indisponibilit\u00e9 des plateformes.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Liens vers d\u2019autres sites Web et publicit\u00e9s<\/h4>\n\n\n\n<p>Il peut y avoir sur les sites de m\u00e9dias sociaux des liens ou des publicit\u00e9s se rapportant \u00e0 des sites Web qui ne rel\u00e8vent pas du gouvernement du Canada. Ces liens sont fournis uniquement par courtoisie \u00e0 l\u2019\u00e9gard des utilisateurs. Le gouvernement du Canada n\u2019est pas responsable de l\u2019information relay\u00e9e par ces liens ou ces publicit\u00e9s, pas plus qu\u2019il ne cautionne ces sites et leur contenu.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Suivre, inscrire parmi les favoris et s\u2019abonner<\/h4>\n\n\n\n<p>La d\u00e9cision de l\u2019OSSNR de suivre un compte de m\u00e9dias sociaux, de l\u2019inscrire parmi ses favoris ou de s\u2019y abonner ne signifie pas qu\u2019il approuve ce compte, ce canal, cette page ou ce site; de m\u00eame, lorsqu\u2019il partage du contenu provenant d\u2019un autre utilisateur ou qu\u2019il fournit un lien vers ce contenu, cela ne signifie pas non plus qu\u2019il l\u2019approuve.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Commentaires et interactions<\/h4>\n\n\n\n<p>L\u2019OSSNR lira les commentaires et participera aux discussions l\u00e0 o\u00f9 il y a lieu. Vos contributions et vos commentaires doivent \u00eatre pertinents et respectueux. L\u2019OSSNR ne se prononcera ni sur les questions partisanes ou politiques ni sur les questions qui enfreignent les pr\u00e9sentes modalit\u00e9s. L\u2019OSSNR se r\u00e9serve le droit de supprimer des commentaires et des contributions, et de bloquer des utilisateurs selon les crit\u00e8res suivants :<\/p>\n\n\n\n<p>Les contributions ou les commentaires :<\/p>\n\n\n\n<ul>\n<li>contiennent des renseignements personnels;<\/li>\n\n\n\n<li>comprennent des renseignements prot\u00e9g\u00e9s ou classifi\u00e9s du gouvernement du Canada;<\/li>\n\n\n\n<li>portent atteinte \u00e0 la propri\u00e9t\u00e9 intellectuelle ou aux droits de propri\u00e9t\u00e9;<\/li>\n\n\n\n<li>sont contraires aux principes de la <em>Charte canadienne des droits et libert\u00e9s et de la Loi constitutionnelle de 1982;<\/em><\/li>\n\n\n\n<li>sont racistes, haineux, sexistes, homophobes ou diffamatoires, ou encore contiennent du contenu obsc\u00e8ne ou pornographique, ou y font r\u00e9f\u00e9rence;<\/li>\n\n\n\n<li>sont mena\u00e7ants, violents ou intimidants, ou repr\u00e9sentent du harc\u00e8lement;<\/li>\n\n\n\n<li>sont contraires aux lois f\u00e9d\u00e9rales, provinciales ou territoriales du Canada;<\/li>\n\n\n\n<li>constituent une usurpation d\u2019identit\u00e9, de la publicit\u00e9 ou du pollupostage;<\/li>\n\n\n\n<li>encouragent toute activit\u00e9 criminelle ou incitent \u00e0 commettre des actes criminels;<\/li>\n\n\n\n<li>sont r\u00e9dig\u00e9s dans une langue autre que l\u2019anglais ou le fran\u00e7ais;<\/li>\n\n\n\n<li>enfreignent le pr\u00e9sent avis de toute autre fa\u00e7on.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019OSSNR se r\u00e9serve le droit de signaler des utilisateurs et\/ou leurs commentaires et leurs contributions \u00e0 des fournisseurs tiers de services de m\u00e9dias sociaux afin d\u2019emp\u00eacher la publication d\u2019\u00e9l\u00e9ments de contenu contraires aux pr\u00e9sentes modalit\u00e9s ou encore aux conditions de service ou aux modalit\u00e9s d\u2019utilisation des plateformes de m\u00e9dias sociaux de ces tiers, ou de supprimer toute publication de ce type.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Accessibilit\u00e9 des plateformes de m\u00e9dias sociaux<\/h4>\n\n\n\n<p>Les plateformes de m\u00e9dias sociaux sont des fournisseurs de services tiers et ne sont donc pas tenues de respecter les normes du gouvernement du Canada en mati\u00e8re d\u2019accessibilit\u00e9 du Web.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Droit d\u2019auteur<\/h4>\n\n\n\n<p class=\"translation-block\">Les renseignements que nous publions sont vis\u00e9s par la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-42\/index.html\"><em>Loi sur le droit d\u2019auteur<\/em><\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Protection des renseignements personnels<\/h4>\n\n\n\n<p>Les comptes de m\u00e9dias sociaux ne sont pas des sites Web du gouvernement du Canada et sont uniquement pr\u00e9sents sur des plateformes de fournisseurs de services tiers.<\/p>\n\n\n\n<p>L\u2019OSSNR utilise diverses plateformes de m\u00e9dias sociaux pour vous informer et recueillir vos commentaires sur les services, les programmes et les initiatives du gouvernement. L\u2019OSSNR pourrait, dans certaines circonstances, devoir recueillir des renseignements personnels aupr\u00e8s de vous.<\/p>\n\n\n\n<p><strong>Cette page vous informe sur ce qui suit :<\/strong><\/p>\n\n\n\n<ul>\n<li>notre d\u00e9finition de \u00ab renseignements personnels \u00bb;<\/li>\n\n\n\n<li>notre utilisation des renseignements personnels.<\/li>\n<\/ul>\n\n\n\n<p><strong>La pr\u00e9sente page vous offre \u00e9galement de l\u2019information sur :<\/strong><\/p>\n\n\n\n<ul>\n<li>vos droits et vos responsabilit\u00e9s en ce qui concerne vos renseignements personnels;<\/li>\n\n\n\n<li>la marche \u00e0 suivre en cas de questions ou de pr\u00e9occupation.<\/li>\n<\/ul>\n\n\n\n<p><strong>Les renseignements personnels sont des \u00e9l\u00e9ments d\u2019information vous concernant qui sont enregistr\u00e9s sous diverses formes et qui peuvent \u00eatre utilis\u00e9s pour r\u00e9v\u00e9ler votre identit\u00e9. Voici des exemples de renseignements personnels :<\/strong><\/p>\n\n\n\n<ul>\n<li>votre nom;<\/li>\n\n\n\n<li>vos coordonn\u00e9es;<\/li>\n\n\n\n<li>votre adresse de protocole Internet (IP);<\/li>\n\n\n\n<li>les renseignements associ\u00e9s \u00e0 vos profils sur les m\u00e9dias sociaux;<\/li>\n\n\n\n<li>vos mentions \u00ab J\u2019aime \u00bb ou vos partages sur les m\u00e9dias sociaux.<\/li>\n<\/ul>\n\n\n\n<p>\u00c0 des fins de consultation sur des sujets susceptibles de vous int\u00e9resser ou de participation \u00e0 des activit\u00e9s de sensibilisation, nous pouvons \u00eatre amen\u00e9s \u00e0 recueillir aupr\u00e8s de vous des renseignements biographiques ainsi que vos avis et vos opinions sur divers sujets.<\/p>\n\n\n\n<p><strong>Vos renseignements personnels peuvent \u00eatre utilis\u00e9s pour :<\/strong><\/p>\n\n\n\n<ul>\n<li>r\u00e9pondre \u00e0 vos demandes de renseignements;<\/li>\n\n\n\n<li>compiler des statistiques et produire des rapports;<\/li>\n\n\n\n<li>vous consulter sur des sujets susceptibles de vous int\u00e9resser;<\/li>\n\n\n\n<li>vous permettre de participer \u00e0 des activit\u00e9s de sensibilisation;<\/li>\n\n\n\n<li>favoriser l\u2019\u00e9change d\u2019opinions, de connaissances, d\u2019expertise et de pratiques exemplaires;<\/li>\n\n\n\n<li>\u00e9valuer des programmes.<\/li>\n<\/ul>\n\n\n\n<p>Si vous formulez des contributions ou des commentaires inappropri\u00e9s, ils pourraient \u00eatre supprim\u00e9s. L\u2019OSSNR peut \u00e9galement vous bloquer ou vous signaler \u00e0 des fournisseurs tiers de services de m\u00e9dias sociaux si vos commentaires ou vos contributions enfreignent les modalit\u00e9s relatives aux interactions sur les m\u00e9dias sociaux. \u00c0 cette fin, et dans la mesure n\u00e9cessaire, nous pouvons utiliser et divulguer vos renseignements personnels.<\/p>\n\n\n\n<p>Nous pouvons rendre public le contenu des interactions sur les m\u00e9dias sociaux si nous avons avis\u00e9 les personnes concern\u00e9es \u00e0 l\u2019avance. Nous solliciterons votre consentement avant d\u2019utiliser vos donn\u00e9es personnelles afin de cr\u00e9er des listes de diffusion qui nous permettront de communiquer avec vous au sujet d\u2019\u00e9v\u00e9nements \u00e0 venir ou de vous demander votre avis sur des sujets en particulier.<\/p>\n\n\n\n<p>Nous n\u2019utiliserons aucun renseignement personnel recueilli aupr\u00e8s de vous par l\u2019interm\u00e9diaire de comptes de m\u00e9dias sociaux pour prendre des d\u00e9cisions dans le cadre de processus vous concernant directement.<\/p>\n\n\n\n<p class=\"translation-block\">Les banques de renseignements personnels suivantes d\u00e9crivent la mani\u00e8re dont nous traitons les renseignements recueillis par l\u2019interm\u00e9diaire de nos comptes de m\u00e9dias sociaux : <a href=\"https:\/\/www.canada.ca\/fr\/secretariat-conseil-tresor\/services\/acces-information-protection-reseignements-personnels\/acces-information\/info-source\/fichiers-renseignements-personnels-ordinaires.html#pou914\">Communications publiques (POU 914)<\/a> et <a href=\"https:\/\/www.canada.ca\/fr\/secretariat-conseil-tresor\/services\/acces-information-protection-reseignements-personnels\/acces-information\/info-source\/fichiers-renseignements-personnels-ordinaires.html#pou938\">Activit\u00e9s de sensibilisation (POU 938)<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Vos droits<\/h4>\n\n\n\n<p>Lorsque vous interagissez par l\u2019interm\u00e9diaire des comptes de m\u00e9dias sociaux officiels de l\u2019OSSNR, les renseignements que contient votre profil de m\u00e9dias sociaux peuvent \u00eatre enregistr\u00e9s conform\u00e9ment aux pratiques de la plateforme de m\u00e9dias sociaux concern\u00e9e. Toutefois, vous avez le droit de refuser de nous fournir des renseignements personnels suppl\u00e9mentaires lorsque vous interagissez avec nous sur ces sites de m\u00e9dias sociaux. Un refus n\u2019engendra aucune cons\u00e9quence juridique ou administrative, mais il est possible que vous ne puissiez pas participer \u00e0 une activit\u00e9 en particulier.<\/p>\n\n\n\n<p>Vous pouvez demander l\u2019acc\u00e8s aux renseignements personnels que vous nous avez fournis ou qui ont pu \u00eatre cr\u00e9\u00e9s lors de vos interactions avec nous par l\u2019interm\u00e9diaire de nos comptes de m\u00e9dias sociaux. Nous ne recueillons ni ne conservons ces renseignements pour qu\u2019ils puissent \u00eatre r\u00e9cup\u00e9r\u00e9s. Par cons\u00e9quent, si vous effectuez une demande pour y acc\u00e9der, veuillez indiquer la date et l\u2019heure de l\u2019interaction et tout autre d\u00e9tail qui pourrait nous aider \u00e0 les r\u00e9cup\u00e9rer. Pour acc\u00e9der \u00e0 ces renseignements personnels, vous pouvez remplir le formulaire de demande d\u2019acc\u00e8s correspondant.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Vos responsabilit\u00e9s<\/h4>\n\n\n\n<p>Si vous choisissez d\u2019interagir avec nous sur les m\u00e9dias sociaux, nous vous recommandons de prendre connaissance des modalit\u00e9s correspondantes de l\u2019OSSNR. Nous vous recommandons \u00e9galement de lire les conditions de service et les politiques de confidentialit\u00e9 du fournisseur de la plateforme de m\u00e9dias sociaux et celles des applications que vous utilisez pour acc\u00e9der \u00e0 cette plateforme.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Nos responsabilit\u00e9s<\/h4>\n\n\n\n<p class=\"translation-block\">Chaque fois que nous recueillons des renseignements personnels aupr\u00e8s de vous sur les m\u00e9dias sociaux ou que de tels renseignements sont cr\u00e9\u00e9s \u00e0 la suite de vos interactions avec nous sur ces plateformes, nous devons nous conformer \u00e0 la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/p-21\/index.html\">Loi sur la protection des renseignements personnels<\/a> et \u00e0 la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/a-1\/\">Loi sur l\u2019acc\u00e8s \u00e0 l\u2019information<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Questions et pr\u00e9occupations<\/h4>\n\n\n\n<p class=\"translation-block\">Si vous avez des questions, des commentaires, des pr\u00e9occupations ou des plaintes concernant la mani\u00e8re dont nous recueillons, utilisons et conservons vos renseignements personnels, communiquez avec le coordonnateur ou la coordonnatrice de l\u2019acc\u00e8s \u00e0 l\u2019information et de la protection des renseignements personnels (AIPRP) du Secr\u00e9tariat de l\u2019OSSNR. Vous pouvez communiquer avec cette personne par courriel, \u00e0 l\u2019adresse <a href=\"mailto:ATIP@nsira-ossnr.gc.ca\">ATIP@nsira-ossnr.gc.ca<\/a>, ou par la poste \u00e0 l\u2019adresse suivante :<\/p>\n\n\n\n<p>Office de surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement<br>\u00c0 l\u2019attention de : Service de l\u2019AIPRP de l\u2019OSSNR<br>C.P. 2430, succursale D<br>Ottawa (Ontario)<br>K1P 5W5 Canada<\/p>\n\n\n\n<p>Si vous n\u2019\u00eates pas satisfait de la r\u00e9ponse du Secr\u00e9tariat de l\u2019OSSNR \u00e0 vos pr\u00e9occupations en mati\u00e8re de protection de la vie priv\u00e9e, vous pouvez communiquer avec le Commissariat \u00e0 la protection de la vie priv\u00e9e du Canada, \u00e0 l\u2019adresse suivante :<\/p>\n\n\n\n<p>Commissariat \u00e0 la protection de la vie priv\u00e9e du Canada<br>30, rue Victoria<br>Gatineau, Quebec&nbsp; K1A 1H3<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Langues officielles<\/h4>\n\n\n\n<p class=\"translation-block\">De nombreuses plateformes de m\u00e9dias sociaux proposent des options linguistiques multiples et fournissent des instructions sur la mani\u00e8re d\u2019\u00e9tablir vos pr\u00e9f\u00e9rences. L\u2019OSSNR respecte la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/o-3.01\/index.html\">Loi sur les langues officielles<\/a> et s\u2019engage \u00e0 voir \u00e0 ce que tous les renseignements fournis soient pr\u00e9sent\u00e9s simultan\u00e9ment en fran\u00e7ais et en anglais, et \u00e0 ce que les deux versions soient de qualit\u00e9 \u00e9gale.<\/p>\n\n\n\n<p>Nous r\u00e9pondons aux commentaires dans la langue officielle dans laquelle ils ont \u00e9t\u00e9 publi\u00e9s. Si nous estimons que la r\u00e9ponse peut rev\u00eatir un int\u00e9r\u00eat public g\u00e9n\u00e9ral, nous pouvons r\u00e9pondre \u00e0 un commentaire dans les deux langues officielles.<\/p>\n\n\n\n<p class=\"translation-block\">Nous partageons parfois des liens qui peuvent diriger les utilisateurs vers les sites d\u2019autres organisations ou entit\u00e9s qui ne sont pas assujetties \u00e0 la <a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/o-3.01\/index.html\">Loi sur les langues officielles<\/a> et qui ne sont offerts que dans la ou les langues dans lesquelles ils sont r\u00e9dig\u00e9s.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Questions et demandes des m\u00e9dias<\/h4>\n\n\n\n<p class=\"translation-block\">Les journalistes sont invit\u00e9s \u00e0 envoyer leurs questions \u00e0 l\u2019adresse <a href=\"mailto:MEDIA-MEDIAS@nsira-ossnr.gc.ca\" target=\"_blank\" rel=\"noreferrer noopener\">MEDIA-MEDIAS@nsira-ossnr.gc.ca<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Renseignements archiv\u00e9s sur le Web<\/h3>\n\n\n\n<p class=\"translation-block\">Les renseignements d\u00e9sign\u00e9s comme \u00e9tant archiv\u00e9s sur le Web le sont \u00e0 des fins de r\u00e9f\u00e9rence, de recherche ou de tenue des dossiers. Ces renseignements n\u2019ont pas \u00e9t\u00e9 modifi\u00e9s ou mis \u00e0 jour depuis la date d\u2019archivage. Les pages archiv\u00e9es sur le Web ne sont pas soumises aux normes Web du gouvernement du Canada. Conform\u00e9ment \u00e0 la <a href=\"https:\/\/www.tbs-sct.canada.ca\/pol\/doc-fra.aspx?id=30683\">Politique sur les communications et l\u2019image de marque<\/a>, vous pouvez demander l\u2019acc\u00e8s \u00e0 ces renseignements dans d\u2019autres formats. Pour ce faire, veuillez <a href=\"mailto:MEDIA-MEDIAS@nsira-ossnr.gc.ca\">communiquer avec nous<\/a>.<\/p>\n\n\n\n<p><a id=\"_msocom_1\"><\/a><\/p>\n<\/div><\/div>\n<\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"template-nsira-subpages.php","meta":{"inline_featured_image":false},"categories":[24],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Terms and conditions - National Security and Intelligence Review Agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nsira-ossnr.gc.ca\/fr\/avis\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms and conditions - National Security and Intelligence Review Agency\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nsira-ossnr.gc.ca\/fr\/avis\/\" \/>\n<meta property=\"og:site_name\" content=\"National Security and Intelligence Review Agency\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T17:58:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nsira-ossnr.gc.ca\/terms-and-conditions\/\",\"url\":\"https:\/\/nsira-ossnr.gc.ca\/terms-and-conditions\/\",\"name\":\"Terms and conditions - National Security and Intelligence Review Agency\",\"isPartOf\":{\"@id\":\"https:\/\/nsira-ossnr.gc.ca\/#website\"},\"datePublished\":\"2023-07-13T17:34:20+00:00\",\"dateModified\":\"2024-04-24T17:58:18+00:00\",\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nsira-ossnr.gc.ca\/terms-and-conditions\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nsira-ossnr.gc.ca\/#website\",\"url\":\"https:\/\/nsira-ossnr.gc.ca\/\",\"name\":\"National Security and Intelligence Review Agency\",\"description\":\"Official Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nsira-ossnr.gc.ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terms and conditions - National Security and Intelligence Review Agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nsira-ossnr.gc.ca\/fr\/avis\/","og_locale":"fr_CA","og_type":"article","og_title":"Terms and conditions - National Security and Intelligence Review Agency","og_url":"https:\/\/nsira-ossnr.gc.ca\/fr\/avis\/","og_site_name":"National Security and Intelligence Review Agency","article_modified_time":"2024-04-24T17:58:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nsira-ossnr.gc.ca\/terms-and-conditions\/","url":"https:\/\/nsira-ossnr.gc.ca\/terms-and-conditions\/","name":"Terms and conditions - National Security and Intelligence Review Agency","isPartOf":{"@id":"https:\/\/nsira-ossnr.gc.ca\/#website"},"datePublished":"2023-07-13T17:34:20+00:00","dateModified":"2024-04-24T17:58:18+00:00","inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nsira-ossnr.gc.ca\/terms-and-conditions\/"]}]},{"@type":"WebSite","@id":"https:\/\/nsira-ossnr.gc.ca\/#website","url":"https:\/\/nsira-ossnr.gc.ca\/","name":"National Security and Intelligence Review Agency","description":"Official Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nsira-ossnr.gc.ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages\/5328"}],"collection":[{"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/comments?post=5328"}],"version-history":[{"count":9,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages\/5328\/revisions"}],"predecessor-version":[{"id":7585,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages\/5328\/revisions\/7585"}],"wp:attachment":[{"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/media?parent=5328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/categories?post=5328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/tags?post=5328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}