{"id":3692,"date":"2022-02-09T13:39:54","date_gmt":"2023-02-27T18:39:57","guid":{"rendered":"https:\/\/nsirademosite.mbeaudry.ca\/?page_id=3692"},"modified":"2026-02-02T15:50:42","modified_gmt":"2026-02-02T20:50:42","slug":"departmental-plan-2022-2023","status":"publish","type":"page","link":"https:\/\/nsira-ossnr.gc.ca\/fr\/secretariat\/operations-du-secretariat\/departmental-plan-2022-2023\/","title":{"rendered":"Plan minist\u00e9riels : 2022-2023"},"content":{"rendered":"<style>\n.share-row-container {\n    display: flex;\n    flex-wrap: nowrap;\n    justify-content: center;\n    gap: 10px;\n    border-radius: 10px;\n    list-style: none;\n}\n.share-item-link {\n    color: #fff !important;\n    padding: 4px 12px;\n    border-radius: 5px;\n    text-decoration: none !important;\n    font-size: 14px;\n    display: flex;\n    align-items: center;\n    white-space: nowrap;\n    transition: transform 0.2s;\n}\n.share-item-link:hover { transform: translateY(-2px); }\n.share-text-label { color: #fff; font-weight: bold; padding: 4px 12px; }\n<\/style>\n\n<div id=\"hero-banner-post\" style=\"background:url(\/wp-content\/uploads\/Reports-post-hero.jpg);background-size:cover;background-position:unset;border-width:0 0 10px 0;border-color:#eeeeee;padding:50px 0;\">\n<div class=\"grid-container\">\n<div class=\"grid-row\">\n<div class=\"text-center grid-lg-12 grid-md-12 grid-12\">\n<h1 style=\"font-size: 2.25em; border:none;\" class=\"has-text-color has-white-color wp-block-post-title\">Plan minist\u00e9riels : 2022-2023<\/h1>\n<hr class=\"wp-block-separator has-white-background-color\">\n<div style=\"display:inline-block;text-align:left;\">\n<ul class=\"share-row-container\">\n<li class=\"share-text-label\">Partager sur :<\/li><li>\n        <a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fnsira-ossnr.gc.ca%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fpages%2F3692\" target=\"_blank\" class=\"share-item-link\">\n        <svg viewbox=\"0 0 16 16\" style=\"width:18px;height:18px;vertical-align:middle;margin-right:6px;fill:#fff;\"><path d=\"M16 8.049c0-4.446-3.582-8.05-8-8.05C3.58 0-.002 3.603-.002 8.05c0 4.017 2.926 7.347 6.75 7.951v-5.625h-2.03V8.05H6.75V6.275c0-2.017 1.195-3.131 3.022-3.131.876 0 1.791.157 1.791.157v1.98h-1.009c-.993 0-1.303.621-1.303 1.258v1.51h2.218l-.354 2.326H9.25V16c3.824-.604 6.75-3.934 6.75-7.951\"\/><\/svg>Facebook\n        <\/a>\n    <\/li><li>\n        <a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fnsira-ossnr.gc.ca%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fpages%2F3692\" target=\"_blank\" class=\"share-item-link\">\n        <svg viewbox=\"0 0 16 16\" style=\"width:18px;height:18px;vertical-align:middle;margin-right:6px;fill:#fff;\"><path d=\"M0 1.146C0 .513.526 0 1.175 0h13.65C15.474 0 16 .513 16 1.146v13.708c0 .633-.526 1.146-1.175 1.146H1.175C.526 16 0 15.487 0 14.854zm4.943 12.248V6.169H2.542v7.225zm-1.2-8.212c.837 0 1.358-.554 1.358-1.248-.015-.709-.52-1.248-1.342-1.248S2.4 3.226 2.4 3.934c0 .694.521 1.248 1.327 1.248zm4.908 8.212V9.359c0-.216.016-.432.08-.586.173-.431.568-.878 1.232-.878.869 0 1.216.662 1.216 1.634v3.865h2.401V9.25c0-2.22-1.184-3.252-2.764-3.252-1.274 0-1.845.7-2.165 1.193v.025h-.016l.016-.025V6.169h-2.4c.03.678 0 7.225 0 7.225z\"\/><\/svg>LinkedIn\n        <\/a>\n    <\/li><li>\n        <a href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fnsira-ossnr.gc.ca%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fpages%2F3692\" target=\"_blank\" class=\"share-item-link\">\n        <svg viewbox=\"0 0 16 16\" style=\"width:18px;height:18px;vertical-align:middle;margin-right:6px;fill:#fff;\"><path d=\"M12.6.75h2.454l-5.36 6.142L16 15.25h-4.937l-3.867-5.07-4.425 5.07H.316l5.733-6.57L0 .75h5.063l3.495 4.633L12.601.75Zm-.86 13.028h1.36L4.323 2.145H2.865z\"\/><\/svg>X\n        <\/a>\n    <\/li><li>\n        <a href=\"https:\/\/www.youtube.com\/\" target=\"_blank\" class=\"share-item-link\">\n        <svg viewbox=\"0 0 16 16\" style=\"width:18px;height:18px;vertical-align:middle;margin-right:6px;fill:#fff;\"><path d=\"M8.051 1.999h.089c.822.003 4.987.033 6.11.335a2.01 2.01 0 0 1 1.415 1.42c.101.38.172.883.22 1.402l.01.104.022.26.008.104c.065.914.073 1.77.074 1.957v.075c-.001.194-.10 1.108-.082 2.06l-.008.105-.009.104c-.05.572-.124 1.14-.235 1.558a2.01 2.01 0 0 1-1.415 1.42c-1.16.312-5.569.334-6.18.335h-.142c-.309 0-1.587-.006-2.927-.052l-.17-.006-.087-.004-.171-.007-.171-.007c-1.11-.049-2.167-.128-2.654-.26a2.01 2.01 0 0 1-1.415-1.419c-.111-.417-.185-.986-.235-1.558L.09 9.82l-.008-.104A31 31 0 0 1 0 7.68v-.123c.002-.215.01-.958.064-1.778l.007-.103.003-.052.008-.104.022-.26.01-.104c.048-.519.119-1.023.22-1.402a2.01 2.01 0 0 1 1.415-1.42c.487-.13 1.544-.21 2.654-.26l.17-.007.172-.006.086-.003.171-.007A100 100 0 0 1 7.858 2zM6.4 5.209v4.818l4.157-2.408z\"\/><\/svg>YouTube\n        <\/a>\n    <\/li><li>\n        <a href=\"https:\/\/bsky.app\/\" target=\"_blank\" class=\"share-item-link\">\n        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 640 640\" aria-hidden=\"true\" focusable=\"false\" style=\"width:18px;height:18px;display:inline-block;vertical-align:middle;margin-right:6px;fill:#fff;\"><path d=\"M439.8 358.7C436.5 358.3 433.1 357.9 429.8 357.4C433.2 357.8 436.5 358.3 439.8 358.7zM320 291.1C293.9 240.4 222.9 145.9 156.9 99.3C93.6 54.6 69.5 62.3 53.6 69.5C35.3 77.8 32 105.9 32 122.4C32 138.9 41.1 258 47 277.9C66.5 343.6 136.1 365.8 200.2 358.6C203.5 358.1 206.8 357.7 210.2 357.2C206.9 357.7 203.6 358.2 200.2 358.6C106.3 372.6 22.9 406.8 132.3 528.5C252.6 653.1 297.1 501.8 320 425.1C342.9 501.8 369.2 647.6 505.6 528.5C608 425.1 533.7 372.5 439.8 358.6C436.5 358.2 433.1 357.8 429.8 357.3C433.2 357.7 436.5 358.2 439.8 358.6C503.9 365.7 573.4 343.5 593 277.9C598.9 258 608 139 608 122.4C608 105.8 604.7 77.7 586.4 69.5C570.6 62.4 546.4 54.6 483.2 99.3C417.1 145.9 346.1 240.4 320 291.1z\"\/><\/svg>Bluesky\n        <\/a>\n    <\/li><li>\n        <a href=\"https:\/\/substack.com\/\" target=\"_blank\" class=\"share-item-link\">\n        <svg viewbox=\"0 0 16 16\" style=\"width:18px;height:18px;vertical-align:middle;margin-right:6px;fill:#fff;\"><path d=\"M15 3.604H1v1.891h14v-1.89ZM1 7.208V16l7-3.926L15 16V7.208zM15 0H1v1.89h14z\"\/><\/svg>Substack\n        <\/a>\n    <\/li><\/ul><\/div><\/div><\/div><\/div><\/div>\n\n\n<section id=\"gm4f29f92\" class=\"wp-block-gutentor-m4 section-gm4f29f92 gutentor-module gutentor-advanced-columns has-color-bg has-custom-bg\"><div class=\"grid-container\"><div class=\"grid-row\">\n<div id=\"col-gm3115c0\" class=\"wp-block-gutentor-m4-col col-gm3115c0 gutentor-single-column  grid-lg-12 grid-md-12 grid-12\"><div id=\"section-gm3115c0\" class=\"section-gm3115c0 gutentor-col-wrap\">\n<h2 class=\"wp-block-heading no-toc\" id=\"1-meta-data-information\">Informations sur les m\u00e9tadonn\u00e9es<\/h2>\n\n\n\n<p>Num\u00e9ro de cat. : <strong>PS106-6F-PDF<\/strong><br>ISSN:&nbsp;<strong>2563-0334<\/strong><\/p>\n\n\n\n<p>\u00a9 Sa Majest\u00e9 la Reine du Chef du Canada, 2020<\/p>\n<\/div><\/div>\n<\/div><\/div><\/section>\n\n\n\n<section id=\"gm48de450\" class=\"wp-block-gutentor-m4 section-gm48de450 gutentor-module gutentor-advanced-columns .post-content-extra-width .post-content\"><div class=\"grid-container\"><div class=\"grid-row\">\n<div id=\"col-gmd9d881\" class=\"wp-block-gutentor-m4-col col-gmd9d881 gutentor-single-column  grid-lg-3 grid-md-12 grid-12 section-sticky\"><div id=\"section-gmd9d881\" class=\"section-gmd9d881 gutentor-col-wrap\">\n<section id=\"26f0a2\" class=\"wp-block-gutentor-m13 section-26f0a2 gutentor-module gutentor-module-table-of-contents\"><div class=\"grid-container\"><div class=\"g-toc\"><div class=\"g-toc-header\"><div class=\"g-toc-heading\"><div class=\"g-toc-title\">Table des mati\u00e8res<\/div><\/div><\/div><div class=\"g-toc-body\" style=\"display:\"><ol class=\"g-ordered-list\" type=\"none\"><li><a href=\"#1-meta-data-information\">Informations sur les m\u00e9tadonn\u00e9es<\/a><\/li><li><a href=\"#2-message-from-the-chair\">Message de la part du directeur g\u00e9n\u00e9ral<\/a><\/li><li><a href=\"#_Toc2\">Aper\u00e7u de nos plans<\/a><\/li><li><a href=\"#5-core-responsibilities-planned-results-and-resources-and-key-risks\">Responsabilit\u00e9s essentielles : r\u00e9sultats et ressources pr\u00e9vus et principaux risques<\/a><ol class=\"child-list\"><li><a href=\"#6-assist-the-national-security-and-intelligence-review-agency\">Surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et enqu\u00eates sur les plaintes<\/a><\/li><\/ol><\/li><li><a href=\"#13-internal-services-planned-results\">Services internes : r\u00e9sultats pr\u00e9vus<\/a><ol class=\"child-list\"><li><a href=\"#13-description\">Description<\/a><\/li><li><a href=\"#14-planning-highlights\">Faits saillants de la planification<\/a><\/li><\/ol><\/li><li><a href=\"#19-spending-and-human-resources\">D\u00e9penses et ressources humaines pr\u00e9vues<\/a><ol class=\"child-list\"><li><a href=\"#20-planned-spending\">D\u00e9penses pr\u00e9vues<\/a><\/li><li><a href=\"#23-planned-human-resources\">Ressources humaines pr\u00e9vues<\/a><\/li><li><a href=\"#25-estimates-by-vote\">Budget des d\u00e9penses par cr\u00e9dit vot\u00e9<\/a><\/li><li><a href=\"#26-condensed-future-oriented-statement-of-operations\">\u00c9tat des r\u00e9sultats condens\u00e9 prospectif<\/a><\/li><\/ol><\/li><li><a href=\"#section_5\">Renseignements minist\u00e9riels<\/a><ol class=\"child-list\"><li><a href=\"#22-organizational-profile\">Profil organisationnel<\/a><\/li><li><a href=\"#section_5_2\">Raison d\u2019\u00eatre, mandat et r\u00f4le : composition et responsabilit\u00e9s<\/a><\/li><li><a href=\"#24-operating-context\">Contexte op\u00e9rationnel<\/a><\/li><li><a href=\"#section_5_3\">Cadre de pr\u00e9sentation de rapports<\/a><\/li><li><a href=\"#section_5_4\">Renseignements connexes sur le R\u00e9pertoire des programmes<\/a><\/li><li><a href=\"#section_5_5\">Tableaux de renseignements suppl\u00e9mentaires<\/a><\/li><li><a href=\"#section_5_6\">D\u00e9penses fiscales f\u00e9d\u00e9rales<\/a><\/li><li><a href=\"#section_5_7\">Coordonn\u00e9es de l\u2019organisation<\/a><\/li><\/ol><\/li><li><a href=\"#30-appendix-definitions\">Annexe : d\u00e9finitions<\/a><\/li><\/ol><\/div><\/div><\/div><\/section>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n<\/div><\/div>\n\n\n\n<div id=\"col-gm3aca5a\" class=\"wp-block-gutentor-m4-col col-gm3aca5a gutentor-single-column  grid-lg-9 grid-md-12 grid-12 content-body\"><div id=\"section-gm3aca5a\" class=\"section-gm3aca5a gutentor-col-wrap\">\n<p class=\"mrgn-bttm-0 has-nsira-blue-color has-text-color\"><strong>Date de publication :<\/strong><\/p>\n\n\n<div class=\"mrgn-bttm-lg wp-block-post-date\"><time datetime=\"2022-02-09T13:39:54-05:00\">9 f\u00e9vrier, 2022<\/time><\/div>\n\n\n<div id=\"gm03efef9\" class=\"wp-block-gutentor-m1 section-gm03efef9 gutentor-module gutentor-element-button-group g-btn-horizontal-d g-btn-horizontal-t g-btn-horizontal-m\"><div class=\"gutentor-element-button-group-wrap\">\n<div id=\"section-g4c1527\" class=\"wp-block-gutentor-e2 section-g4c1527 gutentor-element gutentor-element-button\"><span class=\"gutentor-button-wrap\"><a class=\"gutentor-button gutentor-block-button btn-modern1 gutentor-icon-before\" href=\"\/wp-content\/uploads\/DP_22-23_FR.pdf\"><i class=\"gutentor-button-icon fas fa-file-alt\"><\/i><span>T\u00e9l\u00e9charger le PDF<\/span><\/a><\/span><\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"2-message-from-the-chair\">Message de la part du directeur g\u00e9n\u00e9ral<\/h2>\n\n\n\n<p>C\u2019est un grand plaisir de vous pr\u00e9senter le Plan minist\u00e9riel de 2022\u20132023 de l\u2019Office de surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement (OSSNR ou Office). Le pr\u00e9sent rapport d\u00e9crit nos activit\u00e9s, nos priorit\u00e9s et nos r\u00e9sultats attendus pour l\u2019exercice 2022\u20132023.<\/p>\n\n\n\n<p>Au cours des deux derni\u00e8res ann\u00e9es, l\u2019OSSNR a mis l\u2019accent sur la r\u00e9ussite et l\u2019efficacit\u00e9 de la transition vers une organisation beaucoup plus grande au mandat beaucoup plus vaste, tout en veillant \u00e0 la normalisation et \u00e0 la modernisation des processus qui sous-tendent ses activit\u00e9s. L\u2019Office a vu son effectif cro\u00eetre et son expertise technique et professionnelle se renforcer.<\/p>\n\n\n\n<p class=\" translation-block\"><p>En 2022\u20132023, nous mettrons en \u0153uvre le nouveau plan d\u2019examen triennal de l\u2019OSSNR, qui pr\u00e9voit des examens \u00e9largis et plus complexes au fur et \u00e0 mesure que nous nous familiarisons avec les activit\u00e9s des minist\u00e8res et organismes qui font l\u2019objet de nos examens depuis peu. Cela comprend l\u2019examen des activit\u00e9s men\u00e9es en vertu des pouvoirs conf\u00e9r\u00e9s par la <em>Loi de 2017 sur la s\u00e9curit\u00e9 nationale<\/em>, et de celles qui touchent les technologies et la collecte de donn\u00e9es.<\/p><\/p>\n\n\n\n<p>Au cours de la prochaine ann\u00e9e, nous continuerons de mettre en \u0153uvre notre nouveau processus lanc\u00e9 en 2021 pour le traitement des plaintes du public et les enqu\u00eates connexes. L\u2019OSSNR a consult\u00e9 de nombreux intervenants cl\u00e9s pour concevoir ce nouveau processus, qui vise \u00e0 rendre notre service d\u2019enqu\u00eate sur les plaintes plus accessible et plus rapide.<\/p>\n\n\n\n<p>Alors que nous continuons de renforcer nos activit\u00e9s en 2022\u20132023, notre priorit\u00e9 demeure la sant\u00e9 et la s\u00e9curit\u00e9 de notre personnel. Parmi nos initiatives pr\u00e9vues, mentionnons notre expansion vers un deuxi\u00e8me emplacement, le recrutement d\u2019employ\u00e9s dans tous les secteurs d\u2019activit\u00e9 et le soutien au personnel et aux membres de l\u2019OSSNR. En plus de miser sur nos r\u00e9ussites et de maintenir des objectifs organisationnels ambitieux, nous continuerons de mettre l\u2019accent sur la diversit\u00e9 et l\u2019inclusion en milieu de travail, notamment en \u00e9laborant une strat\u00e9gie d\u2019\u00e9quit\u00e9 en mati\u00e8re d\u2019emploi.<\/p>\n\n\n\n<p>Je tiens \u00e0 remercier le personnel et les membres de l\u2019OSSNR. Ils font preuve de d\u00e9vouement et de r\u00e9silience et ils visent l\u2019excellence. Je me r\u00e9jouis \u00e0 l\u2019id\u00e9e de participer avec eux \u00e0 la croissance de l\u2019OSSNR.<\/p>\n\n\n\n<p>John Davies<br>Directeur g\u00e9n\u00e9ral<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"_Toc2\">Aper\u00e7u de nos plans<\/h2>\n\n\n\n<p>Au cours de la prochaine ann\u00e9e, l\u2019OSSNR poursuivra son ambitieux programme d\u2019examen. Voici en quoi cela consiste :<\/p>\n\n\n\n<ul>\n<li>des examens obligatoires li\u00e9s au Service canadien du renseignement de s\u00e9curit\u00e9 (SCRS), au Centre de la s\u00e9curit\u00e9 des t\u00e9l\u00e9communications (CST), \u00e0 la&nbsp;<em>Loi sur la communication d\u2019information ayant trait \u00e0 la s\u00e9curit\u00e9 du Canada<\/em>&nbsp;et sur les instructions du gouverneur en conseil en rapport avec la&nbsp;<em>Loi visant \u00e0 \u00e9viter la complicit\u00e9 dans les cas de mauvais traitements inflig\u00e9s par des entit\u00e9s \u00e9trang\u00e8res<\/em>;<\/li>\n\n\n\n<li>des examens d\u2019activit\u00e9s entreprises en vertu des nouveaux pouvoirs accord\u00e9s aux institutions f\u00e9d\u00e9rales en vertu de la&nbsp;<em>Loi de 2017 sur la s\u00e9curit\u00e9 nationale<\/em>;<\/li>\n\n\n\n<li>des examens d\u2019activit\u00e9s touchant principalement les technologies et la collecte de donn\u00e9es.<\/li>\n<\/ul>\n\n\n\n<p>L\u2019OSSNR continuera \u00e9galement d\u2019approfondir sa connaissance des minist\u00e8res et des organismes qui ne faisaient pas l\u2019objet d\u2019un examen par des experts auparavant, notamment en menant des examens interorganismes.<\/p>\n\n\n\n<p>Apr\u00e8s un vaste exercice de consultation aupr\u00e8s des principaux intervenants et l\u2019\u00e9laboration de nouvelles r\u00e8gles de proc\u00e9dure en 2021, l\u2019OSSNR se concentrera \u00e9galement sur la mise en \u0153uvre de son nouveau mod\u00e8le d\u2019enqu\u00eate sur les plaintes. L\u2019objectif de l\u2019Office est d\u2019am\u00e9liorer l\u2019acc\u00e8s \u00e0 la justice pour les plaignants et de veiller \u00e0 ce que les enqu\u00eates sur les plaintes soient men\u00e9es en temps opportun.<\/p>\n\n\n\n<p>La sant\u00e9 et le bien-\u00eatre des employ\u00e9s sont essentiels au succ\u00e8s de l\u2019organisation. \u00c0 cet \u00e9gard, l\u2019OSSNR continuera de prendre des mesures pour prot\u00e9ger la sant\u00e9 physique et mentale de ses employ\u00e9s et contribuer \u00e0 r\u00e9duire le stress caus\u00e9 par la pand\u00e9mie. L\u2019OSSNR mettra l\u2019accent sur l\u2019adoption d\u2019initiatives visant \u00e0 am\u00e9liorer le milieu de travail et le bien-\u00eatre des employ\u00e9s ainsi qu\u2019\u00e0 atteindre les objectifs de la fonction publique f\u00e9d\u00e9rale en ce qui a trait \u00e0 la diversit\u00e9, \u00e0 l\u2019inclusion et \u00e0 l\u2019\u00e9quit\u00e9 en mati\u00e8re d\u2019emploi.<\/p>\n\n\n\n<p>Pour de plus amples renseignements sur les plans de l\u2019OSSNR, consulter la section \u00ab Responsabilit\u00e9s essentielles : r\u00e9sultats et ressources pr\u00e9vus et principaux risques \u00bb du pr\u00e9sent plan.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"5-core-responsibilities-planned-results-and-resources-and-key-risks\">Responsabilit\u00e9s essentielles : r\u00e9sultats et ressources pr\u00e9vus et principaux risques<\/h2>\n\n\n\n<p>La pr\u00e9sente section renferme de l\u2019information sur les ressources et les r\u00e9sultats pr\u00e9vus de l\u2019organisation pour chacune de ses responsabilit\u00e9s essentielles. Elle contient \u00e9galement des renseignements sur les principaux risques li\u00e9s \u00e0 l\u2019atteinte de ces r\u00e9sultats.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"6-assist-the-national-security-and-intelligence-review-agency\">Surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et enqu\u00eates sur les plaintes<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"6-description\">Description<\/h4>\n\n\n\n<p>L\u2019OSSNR surveille les activit\u00e9s du gouvernement du Canada en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement pour d\u00e9terminer si elles sont l\u00e9gales, raisonnables et n\u00e9cessaires. Il enqu\u00eate sur les plaintes du public qui se rapportent aux activit\u00e9s du SCRS et du CST ou aux activit\u00e9s de s\u00e9curit\u00e9 nationale de la Gendarmerie Royale du Canada (GRC), ainsi que sur certaines autres plaintes li\u00e9es \u00e0 la s\u00e9curit\u00e9 nationale. Cet examen ind\u00e9pendant permet de renforcer le cadre de responsabilisation applicable aux activit\u00e9s de s\u00e9curit\u00e9 nationale et de renseignement qui sont r\u00e9alis\u00e9es par les institutions du gouvernement du Canada, en plus de pr\u00e9server la confiance du public \u00e0 cet \u00e9gard.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"7-planning-highlights\">Faits saillants de la planification<\/h4>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"8-reviews\">Examens<\/h5>\n\n\n\n<p>\u00c0 l\u2019appui de ce r\u00e9sultat, l\u2019OSSNR continuera de mettre en \u0153uvre un ambitieux programme d\u2019examen en 2022\u20132023. Il examinera les activit\u00e9s du SCRS et du CST afin de fournir aux ministres responsables et au public canadien une \u00e9valuation \u00e9clair\u00e9e de ces activit\u00e9s, notamment leur caract\u00e8re l\u00e9gal, raisonnable et n\u00e9cessaire. L\u2019OSSNR s\u2019appuiera \u00e9galement sur les connaissances qu\u2019il a acquises des minist\u00e8res et organismes, comme la GRC, l\u2019Agence des services frontaliers du Canada (ASFC), Immigration, R\u00e9fugi\u00e9s et Citoyennet\u00e9 Canada, le minist\u00e8re de la D\u00e9fense nationale et les Forces arm\u00e9es canadiennes. Gr\u00e2ce \u00e0 ces connaissances, l\u2019OSSNR veillera \u00e0 ce que les activit\u00e9s de s\u00e9curit\u00e9 nationale ou de renseignement de ces organisations soient examin\u00e9es de mani\u00e8re ind\u00e9pendante. L\u2019OSSNR s\u2019est engag\u00e9 \u00e0 transcender les vases clos qui ont caract\u00e9ris\u00e9 l\u2019examen de la s\u00e9curit\u00e9 nationale et \u00ab suivra le cours \u00bb d\u2019une activit\u00e9 entre les organismes pour s\u2019assurer que ses \u00e9valuations refl\u00e8tent l\u2019approche complexe et int\u00e9gr\u00e9e que le Canada adopte en mati\u00e8re de s\u00e9curit\u00e9 nationale.<\/p>\n\n\n\n<p class=\" translation-block\"><p>L\u2019OSSNR s\u2019engage \u00e0 faire en sorte que son programme d\u2019examen reste r\u00e9actif et d\u2019actualit\u00e9. En 2022\u20132023, afin d\u2019\u00e9clairer la r\u00e9vision \u00e0 venir de la <em>Loi de 2017 sur la s\u00e9curit\u00e9 nationale<\/em>, l\u2019OSSNR se concentrera sur l\u2019examen des activit\u00e9s effectu\u00e9es en vertu des pouvoirs accord\u00e9s par cette loi. Pour le SCRS, il s\u2019agit notamment de la collecte et de l\u2019utilisation d\u2019ensembles de donn\u00e9es et de la mise en \u0153uvre d\u2019un cadre pour la justification des activit\u00e9s qui contreviennent \u00e0 la loi et qui sont men\u00e9es par des employ\u00e9s d\u00e9sign\u00e9s dans des circonstances particuli\u00e8res dans le cadre de leurs fonctions. Pour le CST, cela comprendra la conduite de cyberop\u00e9rations actives et d\u00e9fensives. Parmi les autres examens de l\u2019OSSNR qui fourniront de l\u2019information \u00e0 cet \u00e9gard, mentionnons les examens annuels de la <em>Loi sur la communication d\u2019information ayant trait \u00e0 la s\u00e9curit\u00e9 du Canada<\/em>, des directives du gouverneur en conseil en vertu de la <em>Loi visant \u00e0 \u00e9viter la complicit\u00e9 dans les cas de mauvais traitements inflig\u00e9s par des entit\u00e9s \u00e9trang\u00e8res<\/em>, et des mesures prises par le SCRS pour r\u00e9duire les menaces \u00e0 la s\u00e9curit\u00e9 du Canada.<\/p><\/p>\n\n\n\n<p>L\u2019OSSNR continuera d\u2019approfondir ses connaissances sur les institutions de s\u00e9curit\u00e9 nationale en menant des examens touchant le financement du terrorisme, l\u2019ing\u00e9rence \u00e9trang\u00e8re et la cybers\u00e9curit\u00e9. L\u2019Office utilisera pleinement ses pouvoirs pour suivre le fil de l\u2019information de multiples organisations en proc\u00e9dant \u00e0 l\u2019examen de la collaboration entre le SCRS et le CST, des mesures prises par le SCRS et la GRC pour contrer les menaces pos\u00e9es par des extr\u00e9mistes violents \u00e0 caract\u00e8re id\u00e9ologique et de l\u2019utilisation de sources humaines par divers minist\u00e8res et organismes.<\/p>\n\n\n\n<p>Enfin, l\u2019OSSNR se concentrera sur certains examens ax\u00e9s sur les technologies et les flux de donn\u00e9es, y compris la collecte et l\u2019utilisation de renseignements de source ouverte au minist\u00e8re de la D\u00e9fense nationale, le cycle de vie de l\u2019information recueillie par le SCRS en vertu d\u2019un mandat et les pratiques de la conservation de renseignements \u00e9lectromagn\u00e9tiques par le CST. L\u2019OSSNR mettra \u00e0 profit son expertise technologique interne et externe pour mener ces examens.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"9-outreach-and-collaboration\">Sensibilisation et collaboration<\/h5>\n\n\n\n<p>L\u2019Office continuera de collaborer avec les intervenants communautaires pour comprendre leurs pr\u00e9occupations au chapitre de la s\u00e9curit\u00e9 nationale et des activit\u00e9s de renseignement. Il continuera \u00e9galement de publier proactivement des versions non classifi\u00e9es de ses rapports tout au long de l\u2019ann\u00e9e, ainsi que des renseignements sur ses plans et ses processus. Le rapport annuel continuera de r\u00e9sumer les conclusions et les recommandations de l\u2019examen de l\u2019OSSNR dans leur contexte, en situant ces \u00e9l\u00e9ments dans une analyse plus large des principales tendances et des grands enjeux que l\u2019OSSNR a observ\u00e9s au cours de l\u2019ann\u00e9e. L\u2019OSSNR terminera une mise \u00e0 jour compl\u00e8te de son processus et de ses proc\u00e9dures d\u2019examen et collaborera avec les entit\u00e9s vis\u00e9es pour les appliquer \u00e0 tous les examens qui d\u00e9butent ou qui en sont aux premi\u00e8res \u00e9tapes.<\/p>\n\n\n\n<p>En 2022\u20132023, l\u2019OSSNR continuera de tirer parti des relations \u00e9troites qu\u2019il a \u00e9tablies avec le Comit\u00e9 des parlementaires sur la s\u00e9curit\u00e9 nationale et le renseignement et le Commissariat \u00e0 la protection de la vie priv\u00e9e du Canada. Il coordonnera ses activit\u00e9s pour s\u2019assurer que l\u2019examen est efficace et exhaustif et \u00e9vite un d\u00e9doublement inutile des efforts.<\/p>\n\n\n\n<p>L\u2019Office tisse \u00e9galement des liens \u00e9troits avec ses \u00e9quivalents internationaux. Il continuera de si\u00e9ger au Conseil de surveillance et d\u2019examen du renseignement du Groupe des cinq (FIORC), qui rassemble des repr\u00e9sentants des organismes d\u2019examen du Canada, des \u00c9tats-Unis, de l\u2019Australie, de la Nouvelle-Z\u00e9lande et du Royaume-Uni. L\u2019OSSNR participera \u00e0 la conf\u00e9rence annuelle du FIORC \u00e0 l\u2019automne 2022. De plus, l\u2019OSSNR participera aux groupes de travail du FIORC, dont le but est de se r\u00e9unir r\u00e9guli\u00e8rement pour discuter de sujets d\u2019int\u00e9r\u00eat commun, comme l\u2019incidence des nouvelles technologies, les enqu\u00eates sur les plaintes du public et l\u2019acc\u00e8s \u00e0 l\u2019information dont disposent les minist\u00e8res vis\u00e9s par les examens. L\u2019OSSNR entend \u00e9galement renouveler ses efforts pour cr\u00e9er de nouveaux partenariats avec d\u2019autres organismes d\u2019examen internationaux.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"10-complaints-investigations\">Enqu\u00eates sur les plaintes<\/h5>\n\n\n\n<p>En 2022\u20132023, l\u2019OSSNR renforcera \u00e9galement la responsabilit\u00e9 des institutions et accro\u00eetra la confiance du public en garantissant la coh\u00e9rence, la qualit\u00e9 et la rapidit\u00e9 des enqu\u00eates sur les plaintes li\u00e9es \u00e0 la s\u00e9curit\u00e9 nationale. L\u2019enqu\u00eate ind\u00e9pendante sur les plaintes joue un r\u00f4le essentiel dans le maintien de la confiance du public \u00e0 l\u2019\u00e9gard des institutions de s\u00e9curit\u00e9 nationale du Canada. En 2022\u20132023, l\u2019OSSNR continuera d\u2019offrir un processus de r\u00e8glement informel en compl\u00e9ment au processus d\u2019enqu\u00eate pour donner suite aux plaintes. L\u2019OSSNR appliquera ses nouvelles r\u00e8gles de proc\u00e9dure pour promouvoir l\u2019accessibilit\u00e9, la rapidit\u00e9 et l\u2019efficacit\u00e9 des enqu\u00eates sur les plaintes. Enfin, l\u2019OSSNR \u00e9tablira de nouvelles normes de service pour les enqu\u00eates sur les plaintes.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"11-gender-based-analysis-plus\">Analyse comparative entre les sexes Plus<\/h5>\n\n\n\n<p>En 2022\u20132023, le Comit\u00e9 consultatif sur la diversit\u00e9, l\u2019inclusion et l\u2019\u00e9quit\u00e9 en mati\u00e8re d\u2019emploi de l\u2019OSSNR examinera ses politiques, ses programmes et ses proc\u00e9dures internes ainsi que son mod\u00e8le de prestation de services externes dans l\u2019optique de l\u2019inclusion, de la diversit\u00e9 et de l\u2019\u00e9quit\u00e9, et fournira des conseils \u00e0 ce sujet.<\/p>\n\n\n\n<p>Pour ce qui est de l\u2019ex\u00e9cution des programmes, l\u2019OSSNR travaille en \u00e9troite collaboration avec son partenaire, la Commission civile d\u2019examen et de traitement des plaintes relatives \u00e0 la GRC, afin d\u2019\u00e9laborer des strat\u00e9gies pour la collecte, l\u2019analyse et l\u2019utilisation de donn\u00e9es d\u00e9mographiques et raciales dans le cadre du traitement des plaintes. Cette initiative vise \u00e0 am\u00e9liorer l\u2019acc\u00e8s \u00e0 la justice gr\u00e2ce \u00e0 une sensibilisation accrue et \u00e0 une meilleure compr\u00e9hension du processus d\u2019enqu\u00eate. L\u2019objectif est \u00e9galement de documenter les diff\u00e9rents groupes raciaux parmi les plaignants civils et de v\u00e9rifier :<\/p>\n\n\n\n<ul>\n<li>si des \u00e9carts consid\u00e9rables existent sur le plan racial;<\/li>\n\n\n\n<li>s\u2019il existe des diff\u00e9rences raciales en ce qui concerne les types de plaintes d\u00e9pos\u00e9es contre des membres d\u2019organismes de s\u00e9curit\u00e9 nationale en fonction de diff\u00e9rents groupes;<\/li>\n\n\n\n<li>la fr\u00e9quence des plaintes associ\u00e9es \u00e0 des all\u00e9gations de partialit\u00e9 raciale ou autre;<\/li>\n\n\n\n<li>si les r\u00e9sultats des enqu\u00eates sur les plaintes varient selon le groupe racial;<\/li>\n\n\n\n<li>whether civilian satisfaction with NSIRA\u2019s investigation process also varies by racial group.<\/li>\n<\/ul>\n\n\n\n<p>Le programme d\u2019examens planifi\u00e9s et continus de l\u2019OSSNR tient \u00e9galement compte de la possibilit\u00e9 que des activit\u00e9s de s\u00e9curit\u00e9 nationale et de renseignement entra\u00eenent une disparit\u00e9 des r\u00e9sultats pour des groupes minoritaires. L\u2019examen continu des pratiques de ciblage de l\u2019Agence des services frontaliers du Canada ainsi que du recours \u00e0 la biom\u00e9trie dans un contexte de s\u00e9curit\u00e9 nationale et de renseignement consiste notamment \u00e0 \u00e9valuer l\u2019incidence de ces activit\u00e9s sur divers groupes.<\/p>\n\n\n\n<p>Du point de vue organisationnel, le Comit\u00e9 consultatif sur la diversit\u00e9, l\u2019inclusion et l\u2019\u00e9quit\u00e9 en mati\u00e8re d\u2019emploi continuera \u00e9galement de s\u2019engager aupr\u00e8s du personnel de l\u2019OSSNR sur le plan de la discrimination syst\u00e9mique et du racisme au moyen de s\u00e9minaires et d\u2019activit\u00e9s d\u2019apprentissage. L\u2019objectif est de cr\u00e9er un environnement dans lequel tous les employ\u00e9s se sentent \u00e0 l\u2019aise et n\u2019h\u00e9siteront pas \u00e0 participer aux discussions sur des questions li\u00e9es \u00e0 la lutte contre le racisme, \u00e0 la diversit\u00e9 et \u00e0 l\u2019inclusion.<\/p>\n\n\n\n<p>De plus, l\u2019OSSNR \u00e9labore pour ses employ\u00e9s un processus d\u2019auto-identification qui lui permettra de fa\u00e7onner ses strat\u00e9gies de dotation et d\u2019\u00e9quit\u00e9 en mati\u00e8re d\u2019emploi de mani\u00e8re \u00e0 accro\u00eetre la repr\u00e9sentation et \u00e0 s\u2019assurer que son effectif refl\u00e8te la diversit\u00e9 de la population canadienne.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"12-experimentation\">Exp\u00e9rimentation<\/h5>\n\n\n\n<p>Compte tenu des fonctions et des responsabilit\u00e9s de l\u2019OSSNR, l\u2019organisation ne se livre \u00e0 aucune activit\u00e9 d\u2019exp\u00e9rimentation.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"13-key-risks\">Principaux risques<\/h5>\n\n\n\n<p>La capacit\u00e9 de l\u2019OSSNR d\u2019acc\u00e9der aux renseignements n\u00e9cessaires \u00e0 son travail et de s\u2019entretenir avec les intervenants concern\u00e9s, dans le but de comprendre les politiques, les activit\u00e9s et les probl\u00e8mes actuels, est \u00e9troitement li\u00e9e \u00e0 la capacit\u00e9 des organisations ayant fait l\u2019objet d\u2019un examen de r\u00e9pondre aux demandes de l\u2019OSSNR. Le manque de ressources de ces organisations pourrait continuer de s\u2019aggraver l\u2019ann\u00e9e prochaine en raison des perturbations d\u00e9coulant de la pand\u00e9mie de COVID-19. Cela risque d\u2019entraver la capacit\u00e9 de l\u2019OSSNR de s\u2019acquitter rapidement de son mandat. L\u2019OSSNR att\u00e9nue ce risque en assurant une communication claire au sujet des demandes de renseignements et en \u00e9tablissant des priorit\u00e9s d\u2019examen.<\/p>\n\n\n\n<p>Les pr\u00e9cautions de distanciation physique caus\u00e9es par la pand\u00e9mie de COVID-19 seront probablement toujours n\u00e9cessaires en 2022\u20132023. M\u00eame si l\u2019OSSNR a investi dans la technologie ainsi qu\u2019adapt\u00e9 et \u00e9largi ses espaces de bureau pour r\u00e9pondre \u00e0 ces exigences, la pand\u00e9mie pourrait tout de m\u00eame l\u2019emp\u00eacher d\u2019accomplir son mandat en temps opportun et l\u2019obliger de r\u00e9duire la fr\u00e9quence et l\u2019\u00e9ventail de ses activit\u00e9s de sensibilisation. L\u2019Office continuera d\u2019innover et de s\u2019adapter pour mener ses activit\u00e9s et, au besoin, de communiquer virtuellement avec les intervenants, les minist\u00e8res et les organismes.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"14-planned-results-for-national-security-and-intelligence-activity-reviews-and-complaints-investigations\">R\u00e9sultats pr\u00e9vus pour les examens de la s\u00e9curit\u00e9 nationale et du renseignement et les enqu\u00eates sur les plaintes<\/h4>\n\n\n\n<p>Le tableau ci-dessous pr\u00e9sente, pour la responsabilit\u00e9 essentielle, les examens de la s\u00e9curit\u00e9 nationale et du renseignement et les enqu\u00eates sur les plaintes, les r\u00e9sultats pr\u00e9vus, les indicateurs de r\u00e9sultats, les cibles et les dates cibles pour l\u2019exercice 2022\u20132023 ainsi que les r\u00e9sultats r\u00e9els des trois derniers exercices pour lesquels des r\u00e9sultats r\u00e9els sont disponibles.<\/p>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n\t<thead>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"col\">Indicateurs de r\u00e9sultat minist\u00e9riel<\/th>\n\t\t\t<th class=\"active text-center\" scope=\"col\">Indicateur de r\u00e9sultat minist\u00e9riel<\/th>\n\t\t\t<th class=\"active text-center\" scope=\"col\">Cible<\/th>\n\t\t\t<th class=\"active text-center\" scope=\"col\">Date d\u2019atteinte de la cibles<\/th>\n\t\t\t<th class=\"active text-center\" scope=\"col\">R\u00e9sultat r\u00e9el\n2018\u20132019<\/th>\n\t\t\t<th class=\"active text-center\" scope=\"col\">R\u00e9sultat r\u00e9el\n2019\u20132020<\/th>\n\t\t\t<th class=\"active text-center\" scope=\"col\">R\u00e9sultat r\u00e9el\n2020\u20132021<\/th>\n\t\t<\/tr>\n\t<\/thead>\n\t<tfoot>\n\t\t<tr>\n\t\t\t<td colspan=\"7\">Note : *Puisque l\u2019OSSNR a \u00e9t\u00e9 cr\u00e9\u00e9 le 12 juillet 2019, aucune donn\u00e9e comparative n\u2019est fournie pour 2017\u20132018 et 2018\u20132019. Les r\u00e9sultats r\u00e9els pour 2019\u20132020 ne sont pas disponibles, car le nouveau cadre minist\u00e9riel des r\u00e9sultats dans le transfert du Comit\u00e9 de surveillance des activit\u00e9s de renseignement de s\u00e9curit\u00e9 (CSARS) \u00e0 l\u2019OSSNR \u00e9tait en cours d\u2019\u00e9laboration. Ce nouveau cadre sert \u00e0 mesurer les r\u00e9sultats obtenus \u00e0 partir de 2021\u20132022 et \u00e0 rendre compte \u00e0 cet \u00e9gard.<\/td>\n\t\t<\/tr>\n\t<\/tfoot>\n\t<tbody>\n\t\t<tr>\n\t\t\t<td rowspan=\"3\">Les ministres et les Canadiens sont inform\u00e9s quant \u00e0 savoir si les activit\u00e9s de s\u00e9curit\u00e9 nationale et de renseignement entreprises par les institutions du gouvernement du Canada sont l\u00e9gales, raisonnables et n\u00e9cessaires.<\/td>\n\t\t\t<td>Tous les examens obligatoires sont r\u00e9alis\u00e9s annuellement.<\/td>\n\t\t\t<td>100 % des examens obligatoires ont \u00e9t\u00e9 achev\u00e9s.<\/td>\n\t\t\t<td>D\u00e9cembre 2022<\/td>\n\t\t\t<td>Sans objet (S.O)<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>Des examens portant sur les activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale ou de renseignement d\u2019au moins cinq minist\u00e8res ou organismes f\u00e9d\u00e9raux sont r\u00e9alis\u00e9s chaque ann\u00e9e.<\/td>\n\t\t\t<td>Au moins une activit\u00e9 en mati\u00e8re de s\u00e9curit\u00e9 nationale ou de renseignement est examin\u00e9e dans au moins cinq minist\u00e8res ou organismes f\u00e9d\u00e9raux chaque ann\u00e9e.<\/td>\n\t\t\t<td>D\u00e9cembre 2022<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>Toutes les activit\u00e9s de s\u00e9curit\u00e9 nationale ou de renseignement jug\u00e9es hautement prioritaires approuv\u00e9es par les membres sont examin\u00e9es tous les trois ans<\/td>\n\t\t\t<td>Ach\u00e8vement de 100 % sur trois ans; ach\u00e8vement d\u2019au moins 33 % chaque ann\u00e9e.<\/td>\n\t\t\t<td>D\u00e9cembre 2022<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>Les plaintes relatives \u00e0 la s\u00e9curit\u00e9 nationale font l\u2019objet d\u2019une enqu\u00eate ind\u00e9pendante r\u00e9alis\u00e9e en temps opportun<\/td>\n\t\t\t<td>Pourcentage des enqu\u00eates r\u00e9alis\u00e9es dans le respect des normes de service de l\u2019OSSNR<\/td>\n\t\t\t<td>90%<\/td>\n\t\t\t<td>Mars 2023<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t\t<td>S.O<\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\n\n\n\n<p>Les renseignements sur les ressources financi\u00e8res, les ressources humaines et le rendement li\u00e9s au r\u00e9pertoire des programmes de l\u2019OSSNR sont accessibles dans&nbsp;<a href=\"https:\/\/www.tbs-sct.gc.ca\/ems-sgd\/edb-bdd\/index-fra.html\">l\u2019InfoBase du GC<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"11-planned-budgetary-financial-resources-for-assisting-the-national-security-and-intelligence-review-agency\">Ressources financi\u00e8res budg\u00e9taires pr\u00e9vues pour appuyer l\u2019Office de surveillance\ndes activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement<\/h4>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n<thead>\n<tr>\n<th class=\"active text-center\" scope=\"col\">D\u00e9penses budg\u00e9taires 2022\u20132023 (telles qu\u2019elles sont indiqu\u00e9es dans le Budget principal des d\u00e9penses)<\/th>\n<th class=\"active text-center\" scope=\"col\">D\u00e9penses pr\u00e9vues\n2022-2023<\/th>\n<th class=\"active text-center\" scope=\"col\">D\u00e9penses pr\u00e9vues\n2023\u20132024<\/th>\n<th class=\"active text-center\" scope=\"col\">D\u00e9penses pr\u00e9vues 2024\u20132025<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>10,756,818<\/td>\n<td>10,756,818<\/td>\n<td>10,757,687<\/td>\n<td>10,757,687<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n\n<p>Les renseignements sur les ressources financi\u00e8res, les ressources humaines et le rendement li\u00e9s au r\u00e9pertoire des programmes de l\u2019OSSNR sont accessibles dans&nbsp;<a href=\"https:\/\/www.tbs-sct.gc.ca\/ems-sgd\/edb-bdd\/index-fra.html\">l\u2019InfoBase du GC<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"12-planned-human-resources-for-assisting-the-national-security-and-intelligence-review-agency\">Ressources humaines pr\u00e9vues pour appuyer l\u2019Office de surveillance des activit\u00e9s en\nmati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement<\/h4>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n<thead>\n<tr>\n<th class=\"active text-center\" scope=\"col\">Nombre d\u2019\u00e9quivalents\ntemps plein pr\u00e9vus\n2022-2023<\/th>\n<th class=\"active text-center\" scope=\"col\">Nombre d\u2019\u00e9quivalents temps plein pr\u00e9vus 2023\u20132024<\/th>\n<th class=\"active text-center\" scope=\"col\">Nombre d\u2019\u00e9quivalents temps plein pr\u00e9vus 2024\u20132025<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>69.0<\/td>\n<td>69.0<\/td>\n<td>69.0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n\n<p>Les renseignements sur les ressources financi\u00e8res, les ressources humaines et le rendement li\u00e9s au r\u00e9pertoire des programmes de l\u2019OSSNR sont accessibles dans&nbsp;<a href=\"https:\/\/www.tbs-sct.gc.ca\/ems-sgd\/edb-bdd\/index-fra.html\">l\u2019InfoBase du GC<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"13-internal-services-planned-results\">Services internes : r\u00e9sultats pr\u00e9vus<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"13-description\">Description<\/h3>\n\n\n\n<p>Les services internes sont les services fournis au sein d\u2019un minist\u00e8re afin qu\u2019il puisse respecter ses obligations et ex\u00e9cuter ses programmes. Les dix cat\u00e9gories de services internes sont les suivantes :<\/p>\n\n\n\n<ul>\n<li>services de gestion et de surveillance<\/li>\n\n\n\n<li>services des communications;<\/li>\n\n\n\n<li>services juridiques;<\/li>\n\n\n\n<li>services de gestion des ressources humaines;<\/li>\n\n\n\n<li>Services de gestion des finances<\/li>\n\n\n\n<li>services de gestion de l\u2019information;<\/li>\n\n\n\n<li>services des technologies de l\u2019information;<\/li>\n\n\n\n<li>services de gestion des biens.<\/li>\n\n\n\n<li>Services de gestion du mat\u00e9riel<\/li>\n\n\n\n<li>Services de gestion des acquisitions;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"14-planning-highlights\">Faits saillants de la planification<\/h3>\n\n\n\n<p>Alors qu\u2019il entame sa troisi\u00e8me ann\u00e9e d\u2019activit\u00e9, l\u2019OSSNR continuera de prendre des mesures pour s\u2019assurer que les ressources sont d\u00e9ploy\u00e9es de la mani\u00e8re la plus efficace possible et que ses structures, outils et processus op\u00e9rationnels et administratifs visent toujours l\u2019accomplissement de ses priorit\u00e9s.<\/p>\n\n\n\n<p>Les employ\u00e9s de l\u2019OSSNR sont le moteur de ses activit\u00e9s. Comme leur sant\u00e9 et leur bien-\u00eatre sont essentiels au succ\u00e8s de l\u2019organisation, plusieurs initiatives ax\u00e9es sur la sant\u00e9 en milieu de travail et le bien-\u00eatre des employ\u00e9s constitueront une priorit\u00e9 permanente.<\/p>\n\n\n\n<p>Afin d\u2019attirer et de retenir les talents, l\u2019OSSNR poursuivra ses initiatives visant \u00e0 d\u00e9finir sa vision, ses valeurs, sa culture et sa marque. L\u2019Office collaborera avec ses employ\u00e9s pour \u00e9tablir un cadre de travail hybride et des programmes de gestion des talents et de la carri\u00e8re.<\/p>\n\n\n\n<p>L\u2019OSSNR a d\u00e9fini et publi\u00e9 un plan d\u2019action visant \u00e0 soutenir les objectifs de la fonction publique f\u00e9d\u00e9rale li\u00e9s \u00e0 l\u2019\u00e9quit\u00e9 en mati\u00e8re d\u2019emploi, \u00e0 la diversit\u00e9 et \u00e0 l\u2019inclusion. En 2022\u20132023, l\u2019Office acc\u00e9l\u00e9rera ses efforts \u00e0 ce chapitre.<\/p>\n\n\n\n<p>S\u2019il n\u2019est pas retard\u00e9 davantage par la pand\u00e9mie, l\u2019OSSNR entend terminer ses investissements dans les locaux, l\u2019infrastructure et les syst\u00e8mes au cours de 2022\u20132023 et \u00e9valuer sa conformit\u00e9 avec les politiques et les directives des organismes centraux.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"16-planned-budgetary-financial-resources-for-internal-services\">Ressources financi\u00e8res budg\u00e9taires pr\u00e9vues pour les Services internes<\/h4>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n<thead>\n<tr>\n<th class=\"active text-center\" scope=\"col\">D\u00e9penses budg\u00e9taires 2022\u20132023 (telles qu\u2019elles sont indiqu\u00e9es dans le Budget principal des d\u00e9penses)<\/th>\n<th class=\"active text-center\" scope=\"col\">D\u00e9penses pr\u00e9vues\n2022-2023<\/th>\n<th class=\"active text-center\" scope=\"col\">D\u00e9penses pr\u00e9vues\n2023\u20132024<\/th>\n<th class=\"active text-center\" scope=\"col\">D\u00e9penses pr\u00e9vues 2024\u20132025<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>17,493,858<\/td>\n<td>17,493,858<\/td>\n<td>7,701,336<\/td>\n<td>7,701,042<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"17-planned-human-resources-for-internal-services\">Ressources humaines pr\u00e9vues pour les Services internes<\/h4>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n<thead>\n<tr>\n<th class=\"active text-center\" scope=\"col\">Nombre d\u2019\u00e9quivalents\ntemps plein pr\u00e9vus\n2022-2023<\/th>\n<th class=\"active text-center\" scope=\"col\">Nombre d\u2019\u00e9quivalents temps plein pr\u00e9vus 2023\u20132024<\/th>\n<th class=\"active text-center\" scope=\"col\">Nombre d\u2019\u00e9quivalents temps plein pr\u00e9vus 2024\u20132025<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>31.0<\/td>\n<td>31.0<\/td>\n<td>31.0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"19-spending-and-human-resources\">D\u00e9penses et ressources humaines pr\u00e9vues<\/h2>\n\n\n\n<p>Cette section donne un aper\u00e7u des d\u00e9penses et des ressources humaines du minist\u00e8re pr\u00e9vues pour les trois prochains exercices et compare les d\u00e9penses pr\u00e9vues pour l\u2019exercice 2022\u20132023 avec les d\u00e9penses r\u00e9elles pour l\u2019exercice en cours et l\u2019exercice pr\u00e9c\u00e9dent.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"20-planned-spending\">D\u00e9penses pr\u00e9vues<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"21-departmental-spending-2017%E2%80%9318-to-2022%E2%80%9323\"><strong>D\u00e9penses minist\u00e9rielles de 2019\u20132020 \u00e0 2024\u20132025<\/strong><\/h4>\n\n\n\n<p>Le graphique ci-dessous pr\u00e9sente les d\u00e9penses pr\u00e9vues (vot\u00e9es et l\u00e9gislatives) au fil du temps.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"\/wp-content\/uploads\/dp_22-23_fig01-eng-1024x613.png\" alt=\"\" class=\"wp-image-3702\" width=\"768\" height=\"460\" srcset=\"https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig01-eng-1024x613.png 1024w, https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig01-eng-300x180.png 300w, https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig01-eng-768x460.png 768w, https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig01-eng-18x12.png 18w, https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig01-eng.png 1105w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<details><summary aria-expanded=\"false\" role=\"button\">Version texte de la figure 1<\/summary>\n\n\t<table class=\"table table-striped table-bordered small\">\n\t\t<caption class=\"text-left\"><span><span>Graphique des tendances relatives aux d\u00e9penses du Minist\u00e8re<\/span><\/span><\/caption>\n\t\t<thead>\n\t\t\t<tr>\n\t\t\t\t<th class=\"active text-center\" scope=\"col\">&nbsp;<\/th>\n\t\t\t\t<th class=\"active text-center\" scope=\"col\">2019\u201320<\/th>\n\t\t\t\t<th class=\"active text-center\" scope=\"col\">2020\u201321<\/th>\n\t\t\t\t<th class=\"active text-center\" scope=\"col\">2021\u201322<\/th>\n\t\t\t\t<th class=\"active text-center\" scope=\"col\">2022\u201323<\/th>\n\t\t\t\t<th class=\"active text-center\" scope=\"col\">2023\u201324<\/th>\n\t\t\t\t<th class=\"active text-center\" scope=\"col\">2024\u201325<\/th>\n\t\t\t<\/tr>\n\t\t<\/thead>\n\t\t<tbody>\n\t\t\t<tr>\n\t\t\t\t<th class=\"active text-center\" scope=\"row\">Postes l\u00e9gislatives<\/th>\n\t\t\t\t<td>371,057<\/td>\n\t\t\t\t<td>962,186<\/td>\n\t\t\t\t<td>1,295,290<\/td>\n\t\t\t\t<td>1,727,668<\/td>\n\t\t\t\t<td>1,727,668<\/td>\n\t\t\t\t<td>1,727,668<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<th class=\"active text-center\" scope=\"row\">Cr\u00e9dit vot\u00e9s<\/th>\n\t\t\t\t<td>5,254,250<\/td>\n\t\t\t\t<td>11,289,189<\/td>\n\t\t\t\t<td>19,137,337<\/td>\n\t\t\t\t<td>26,523,008<\/td>\n\t\t\t\t<td>16,731,355<\/td>\n\t\t\t\t<td>16,731,061<\/td>\n\t\t\t<\/tr>\n\t\t\t<tr>\n\t\t\t\t<th class=\"active text-center\" scope=\"row\">Total<\/th>\n\t\t\t\t<td>5,625,250<\/td>\n\t\t\t\t<td>12,251,375<\/td>\n\t\t\t\t<td>20,432,627<\/td>\n\t\t\t\t<td>28,250,676<\/td>\n\t\t\t\t<td>18,435,987<\/td>\n\t\t\t\t<td>18,458,729<\/td>\n\t\t\t<\/tr>\n\t\t<\/tbody>\n\t<\/table>\n\t<\/details>\n\n\n\n<p>Pour les exercices 2019\u20132020 et 2020\u20132021, les d\u00e9penses indiqu\u00e9es sont les d\u00e9penses r\u00e9elles telles qu\u2019elles figurent dans les Comptes publics, tandis que les d\u00e9penses associ\u00e9es \u00e0 l\u2019exercice 2021\u20132022 sont les pr\u00e9visions pour l\u2019exercice en cours. Pour les exercices 2022\u20132023 \u00e0 2024\u20132025, les d\u00e9penses illustr\u00e9es sont les d\u00e9penses pr\u00e9vues.<\/p>\n\n\n\n<p>Les d\u00e9penses de 12,2 millions de dollars en 2020\u20132021 ont augment\u00e9 de 6,6 millions de dollars (118 %) par rapport \u00e0 2019\u20132020. L\u2019augmentation est attribuable au fait que l\u2019OSSNR a \u00e9t\u00e9 cr\u00e9\u00e9 en juillet 2019, de sorte que les d\u00e9penses r\u00e9elles pour 2019\u20132020 refl\u00e8tent une partie de l\u2019exercice seulement. Les d\u00e9penses pr\u00e9vues en 2021\u20132022 sont plus \u00e9lev\u00e9es que les d\u00e9penses de 2020\u20132021, soit 8,2 million de dollars (67 %) de plus, principalement en raison d\u2019une augmentation de l\u2019effectif et des investissements limit\u00e9s dans les locaux, l\u2019infrastructure et les syst\u00e8mes.<\/p>\n\n\n\n<p>Nous pr\u00e9voyons que les d\u00e9penses augmenteront de 7,8 millions de dollars (38 %) en 2022\u20132023 par rapport \u00e0 2021\u20132022. Cette augmentation pr\u00e9vue est principalement attribuable \u00e0 un report de fonds qui vise \u00e0 harmoniser le financement avec la r\u00e9alisation de projets retard\u00e9s par la pand\u00e9mie. Les d\u00e9penses devraient diminuer de 9,8 millions de dollars (35 %) en 2023\u20132024, principalement en raison de l\u2019ach\u00e8vement pr\u00e9vu du projet d\u2019expansion des bureaux en 2022\u20132023. Les d\u00e9penses devraient encore rester les m\u00eames en 2024\u20132025 de 2023\u20132024.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"18-budgetary-financial-resources-dollars\">Sommaire de la planification budg\u00e9taire pour les responsabilit\u00e9s essentielles et les\nServices internes (en dollars)<\/h4>\n\n\n\n<p>Le tableau ci-dessous pr\u00e9sente des renseignements sur les d\u00e9penses pour chaque responsabilit\u00e9 essentielle de l\u2019OSSNR et pour ses services internes pour 2022\u20132023 et les autres exercices pertinents.<\/p>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n\t<thead>\n\t\t<tr>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Responsabilit\u00e9s essentielles et Services internes<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">D\u00e9penses r\u00e9elles 2019\u20132020<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">D\u00e9penses r\u00e9elles 2020\u20132021<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Pr\u00e9visions des d\u00e9penses 2021\u20132022<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">D\u00e9penses budg\u00e9taires 2022\u20132023 (telles qu\u2019elles sont indiqu\u00e9es dans le Budget principal des d\u00e9penses)<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">D\u00e9penses pr\u00e9vues\n2022-2023<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">D\u00e9penses pr\u00e9vues\n2023\u20132024<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">D\u00e9penses pr\u00e9vues 2024\u20132025<\/th>\n\t\t<\/tr>\n\t<\/thead>\n\t<tbody>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et enqu\u00eates sur les plaintes<\/th>\n\t\t\t<td>3,009,066<\/td>\n\t\t\t<td>5,607,796<\/td>\n\t\t\t<td>8,074,229<\/td>\n\t\t\t<td>10,756,818<\/td>\n\t\t\t<td>10,756,818<\/td>\n\t\t\t<td>10,757,687<\/td>\n\t\t\t<td>10,757,687<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Total partiel<\/th>\n\t\t\t<td>3,009,066<\/td>\n\t\t\t<td>5,607,796<\/td>\n\t\t\t<td>8,074,229<\/td>\n\t\t\t<td>10,756,818<\/td>\n\t\t\t<td>10,756,818<\/td>\n\t\t\t<td>10,757,687<\/td>\n\t\t\t<td>10,757,687<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Services internes<\/th>\n\t\t\t<td>2,616,241<\/td>\n\t\t\t<td>6,643,579<\/td>\n\t\t\t<td>12,358,398<\/td>\n\t\t\t<td>17,493,858<\/td>\n\t\t\t<td>17,493,858<\/td>\n\t\t\t<td>7,701,336<\/td>\n\t\t\t<td>7,701,042<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Total<\/th>\n\t\t\t<td>5,625,307<\/td>\n\t\t\t<td>12,251,375<\/td>\n\t\t\t<td>20,432,627<\/td>\n\t\t\t<td>28,250,676<\/td>\n\t\t\t<td>28,250,676<\/td>\n\t\t\t<td>18,459,023<\/td>\n\t\t\t<td>18,458,729<\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\n\n\n\n<p>Puisque l\u2019OSSNR a \u00e9t\u00e9 cr\u00e9\u00e9 le 12 juillet 2019, aucune donn\u00e9e comparative n\u2019est fournie pour les ann\u00e9es pr\u00e9c\u00e9dentes. Les chiffres indiqu\u00e9s pour 2019\u20132020 portent sur la p\u00e9riode de rapport comprise entre le 12 juillet 2019 et le 31 mars 2020.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"23-planned-human-resources\">Ressources humaines pr\u00e9vues<\/h3>\n\n\n\n<p>Le tableau ci-dessous pr\u00e9sente des renseignements sur les ressources humaines, en \u00e9quivalents temps plein (ETP), pour chaque responsabilit\u00e9 essentielle de l\u2019OSSNR et pour ses services internes pour 2022\u20132023 et les autres exercices pertinents.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"24-human-resources-planning-summary-for-core-responsibilities-and-internal-services\">Sommaire de la planification des ressources humaines pour les responsabilit\u00e9s\nessentielles et les Services internes<\/h4>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n\t<thead>\n\t\t<tr>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Responsabilit\u00e9s essentielles et Services internes<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Nombre d\u2019\u00e9quivalents temps plein r\u00e9els pour 2019-2020<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Nombre d\u2019\u00e9quivalents temps plein r\u00e9els 2020-2021<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Pr\u00e9visions d\u2019\u00e9quivalents temps plein 2021\u20132022<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">\u00c9quivalents temps plein pr\u00e9vus 2022\u20132023<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">\u00c9quivalents temps plein pr\u00e9vus 2023\u20132024<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">\u00c9quivalents temps plein pr\u00e9vus 2024\u20132025<\/th>\n\t\t<\/tr>\n\t<\/thead>\n\t<tbody>\n\t\t<tr>\n\t\t\t<th scope=\"row\">Surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et enqu\u00eates sur les plaintes<\/th>\n\t\t\t<td>17.5<\/td>\n\t\t\t<td>37.8<\/td>\n\t\t\t<td>53.3<\/td>\n\t\t\t<td>69.0<\/td>\n\t\t\t<td>69.0<\/td>\n\t\t\t<td>69.0<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Total partiel<\/th>\n\t\t\t<td>17.5<\/td>\n\t\t\t<td>37.8<\/td>\n\t\t\t<td>53.3<\/td>\n\t\t\t<td>69.0<\/td>\n\t\t\t<td>69.0<\/td>\n\t\t\t<td>69.0<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Services internes<\/th>\n\t\t\t<td>11.2<\/td>\n\t\t\t<td>21.7<\/td>\n\t\t\t<td>25.9<\/td>\n\t\t\t<td>31.0<\/td>\n\t\t\t<td>31.0<\/td>\n\t\t\t<td>31.0<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Total<\/th>\n\t\t\t<td>28.7<\/td>\n\t\t\t<td>59.5<\/td>\n\t\t\t<td>79.2<\/td>\n\t\t\t<td>100.0<\/td>\n\t\t\t<td>100.0<\/td>\n\t\t\t<td>100.0<\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\n\n\n\n<p>Au cours de 2019-2020, un financement pour 26 ETP suppl\u00e9mentaires a \u00e9t\u00e9 re\u00e7u en vue de tenir compte du mandat \u00e9largi de l\u2019OSSNR. On s\u2019attend \u00e0 ce que l\u2019OSSNR soit \u00e0 pleine capacit\u00e9 d\u2019ici la fin de 2021-2022 pour remplir son nouveau mandat.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"25-estimates-by-vote\">Budget des d\u00e9penses par cr\u00e9dit vot\u00e9<\/h3>\n\n\n\n<p>Des renseignements sur les cr\u00e9dits de l\u2019OSSNR sont accessibles dans le&nbsp;<a href=\"https:\/\/www.canada.ca\/fr\/secretariat-conseil-tresor\/services\/depenses-prevues\/plan-depenses-budget-principal.html\" target=\"_blank\" rel=\"noreferrer noopener\">Budget principal des d\u00e9penses de 2022\u20132023<\/a><a href=\"http:\/\/www.tpsgc-pwgsc.gc.ca\/recgen\/cpc-pac\/index-fra.html\">.<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"26-condensed-future-oriented-statement-of-operations\">\u00c9tat des r\u00e9sultats condens\u00e9 prospectif<\/h3>\n\n\n\n<p>L\u2019\u00e9tat des r\u00e9sultats condens\u00e9s prospectifs donne un aper\u00e7u des op\u00e9rations de l\u2019OSSNR de 2021\u20132022 \u00e0 2022\u20132023.<\/p>\n\n\n\n<p>Les montants projet\u00e9s et pr\u00e9vus de cet \u00e9tat des r\u00e9sultats sont pr\u00e9par\u00e9s selon la m\u00e9thode de comptabilit\u00e9 d\u2019exercice. Les montants projet\u00e9s et pr\u00e9vus pr\u00e9sent\u00e9s dans d\u2019autres sections du plan minist\u00e9riel ont \u00e9t\u00e9 \u00e9tablis selon la m\u00e9thode de comptabilit\u00e9 ax\u00e9e sur les d\u00e9penses. Par cons\u00e9quent, il est possible que les montants diff\u00e8rent.<\/p>\n\n\n\n<p>Un \u00e9tat des r\u00e9sultats prospectif plus d\u00e9taill\u00e9 et des notes aff\u00e9rentes, notamment un rapprochement des co\u00fbts de fonctionnement nets et des autorisations demand\u00e9es, se trouvent sur le&nbsp;<a href=\"https:\/\/nsira-ossnr.gc.ca\/fr\/\">site Web de l\u2019OSSNR<\/a>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"25-future-oriented-condensed-statement-of-operations-for-the-year-ending-march-31-2022-dollars\">\u00c9tat des r\u00e9sultats condens\u00e9 prospectif pour l\u2019exercice se terminant le 31 mars 2022 (en dollars)<\/h4>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n\t<thead>\n\t\t<tr>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Renseignements financiers<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Pr\u00e9visions des r\u00e9sultats 2021\u20132022<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">R\u00e9sultats pr\u00e9vus 2022\u20132023<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">\u00c9cart (r\u00e9sultats pr\u00e9vus 2022\u20132023 moins pr\u00e9visions des r\u00e9sultats 2021\u20132022)<\/th>\n\t\t<\/tr>\n\t<\/thead>\n\t<tbody>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Total des charges<\/th>\n\t\t\t<td>21,850,048<\/td>\n\t\t\t<td>28,625,397<\/td>\n\t\t\t<td>6,775,349<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Total des revenus<\/th>\n\t\t\t<td>&#8211;<\/td>\n\t\t\t<td>&#8211;<\/td>\n\t\t\t<td>&#8211;<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center\" scope=\"row\">Co\u00fbt de fonctionnement net avant le financement du gouvernement et les transferts<\/th>\n\t\t\t<td>21,850,048<\/td>\n\t\t\t<td>28,625,397<\/td>\n\t\t\t<td>6,775,349<\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\n\n\n\n<p>L\u2019\u00e9cart entre les r\u00e9sultats pr\u00e9vus pour 2022\u20132023 et les pr\u00e9visions des r\u00e9sultats de 2021\u20132022 s\u2019explique principalement par des d\u00e9penses pr\u00e9vues pour la r\u00e9alisation de projets de locaux, d\u2019infrastructures et de syst\u00e8mes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"section_5\">Renseignements minist\u00e9riels<\/h2>\n\n\n\n<h3 class=\"wp-block-heading no-toc\" id=\"22-organizational-profile\">Profil organisationnel<\/h3>\n\n\n\n<p><strong>Ministre de tutelle :<\/strong>&nbsp;Le tr\u00e8s honorable Justin Trudeau, premier ministre du Canada<br><strong>Administrateur g\u00e9n\u00e9ral :<\/strong>&nbsp;John Davies, directeur ex\u00e9cutif<br><strong>Portefeuille minist\u00e9riel :<\/strong>&nbsp;Bureau du Conseil priv\u00e9<br><strong>Instrument habilitant:<\/strong>&nbsp;<a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/n-16.62\/page-1.html\">Loi sur l\u2019Office de surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement<\/a><br><strong>Ann\u00e9e d\u2019incorporation ou de cr\u00e9ation :<\/strong>&nbsp;2019<\/p>\n\n\n\n<h3 class=\"wp-block-heading no-toc\" id=\"section_5_2\">Raison d\u2019\u00eatre, mandat et r\u00f4le : composition et responsabilit\u00e9s<\/h3>\n\n\n\n<p class=\" translation-block\"><p>Des renseignements sur la raison d\u2019\u00eatre, le mandat et le r\u00f4le de l\u2019OSSNR se trouvent dans le <a href=\"https:\/\/nsira-ossnr.gc.ca\/fr\/\">site Web de l\u2019OSSNR<\/a>.<\/p><\/p>\n\n\n\n<h3 class=\"wp-block-heading no-toc\" id=\"24-operating-context\">Contexte op\u00e9rationnel<\/h3>\n\n\n\n<p>Des renseignements sur le contexte op\u00e9rationnel sont accessibles sur le&nbsp;<a href=\"https:\/\/nsira-ossnr.gc.ca\/fr\/\">site Web de l\u2019OSSNR<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading no-toc\" id=\"section_5_3\">Cadre de pr\u00e9sentation de rapports<\/h3>\n\n\n\n<p>Le cadre de r\u00e9sultats minist\u00e9riel de l\u2019OSSNR, ainsi que les r\u00e9sultats et indicateurs connexes, sont\nen cours d\u2019\u00e9laboration. Le Plan minist\u00e9riel 2021-2022 fournira des renseignements\nsuppl\u00e9mentaires sur les principales mesures du rendement.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"599\" src=\"\/wp-content\/uploads\/dp_22-23_fig02-eng-1024x599.png\" alt=\"Graphique : Cadre de r\u00e9f\u00e9rence pour l&#039;\u00e9tablissement des rapports - La version texte suit\" class=\"wp-image-3715\" srcset=\"https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig02-eng-1024x599.png 1024w, https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig02-eng-300x176.png 300w, https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig02-eng-768x449.png 768w, https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig02-eng-18x12.png 18w, https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/dp_22-23_fig02-eng.png 1085w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<details><summary aria-expanded=\"false\" role=\"button\">Version texte de la figure 2<\/summary>\n<table class=\"table table-striped table-bordered small\">\n\t<thead>\n\t\t<tr>\n\t\t\t<th class=\"active text-center align-top\" colspan=\"4\" scope=\"col\">Core Responsibility: National Security and Intelligence Reviews and Complaints Investigations<\/th>\n\t\t<\/tr>\n\t<\/thead>\n\t<tbody>\n\t\t<tr>\n\t\t\t<th class=\"active text-center align-middle\" rowspan=\"4\" scope=\"row\">Cadre minist\u00e9riel des r\u00e9sultats<\/th>\n\t\t\t<td rowspan=\"3\">Les ministres et les Canadiens sont inform\u00e9s quant \u00e0 savoir si les activit\u00e9s de s\u00e9curit\u00e9 nationale et de renseignement entreprises par les institutions du gouvernement du Canada sont l\u00e9gales, raisonnables et n\u00e9cessaires.<\/td>\n\t\t\t<td><strong>Indicateur<\/strong>: Tous les examens obligatoires sont r\u00e9alis\u00e9s chaque ann\u00e9e<\/td>\n\t\t\t<td class=\"active text-center align-middle\" rowspan=\"6\">Services internes<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td><strong>Indicateur<\/strong>: Les activit\u00e9s de s\u00e9curit\u00e9 nationale ou de renseignement d'au moins cinq minist\u00e8res ou organismes sont examin\u00e9es chaque ann\u00e9e<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td><strong>Indicateur<\/strong>: Toutes les activit\u00e9s de s\u00e9curit\u00e9 nationale ou de renseignement jug\u00e9es hautement prioritaires approuv\u00e9es par les membres sont examin\u00e9es tous les trous ans<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>Les plaintes relatives \u00e0 la s\u00e9curit\u00e9 nationale font l\u2019objet d\u2019une enqu\u00eate ind\u00e9pendante r\u00e9alis\u00e9e en temps opportun<\/td>\n\t\t\t<td><strong>Indicateur<\/strong>: Pourcentage des enqu\u00eates r\u00e9alis\u00e9es dans le respect des normes de service de l'OSSNR<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th class=\"active text-center align-middle\" rowspan=\"2\" scope=\"row\">R\u00e9pertoire \ndes \nprogrammes<\/th>\n\t\t\t<td colspan=\"2\">Programme: Surveillance des activit\u00e9s de s\u00e9curit\u00e9 nationale et de renseignement et enqu\u00eates sure les plaintes<\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\n<\/details>\n\n\n\n<p>Le transfert du Comit\u00e9 de surveillance des activit\u00e9s de renseignement de s\u00e9curit\u00e9 (CSARS) \u00e0 l\u2019OSSNR a exig\u00e9 que l\u2019on apporte des changements importants au cadre minist\u00e9riel des r\u00e9sultats, aux r\u00e9sultats attendus et aux indicateurs. Compte tenu du mandat plus large de l\u2019OSSNR, ces changements fournissent d\u00e9sormais un cadre permettant de mesurer les r\u00e9sultats atteints \u00e0 partir de 2021-2022 et au-del\u00e0 et d\u2019en rendre compte.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"31-changes-to-the-approved-reporting-framework-since-2020-21\">Changements apport\u00e9s au cadre de pr\u00e9sentation de rapports approuv\u00e9 depuis 2019-2020<\/h4>\n\n\n\n<table class=\"table table-striped table-bordered small\">\n\t<thead>\n\t\t<tr>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Structure<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">2020-21<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">2021-22<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Changement<\/th>\n\t\t\t<th class=\"active text-center align-top\" scope=\"col\">Raison du changement<\/th>\n\t\t<\/tr>\n\t<\/thead>\n\t<tbody>\n\t\t<tr>\n\t\t\t<th scope=\"row\" class=\"active text-center\">Total des charges<\/th>\n\t\t\t<td>Enqu\u00eates sur les activit\u00e9s op\u00e9rationnelles du Service canadien du renseignement de s\u00e9curit\u00e9 (SCRS)<\/td>\n\t\t\t<td>Surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et enqu\u00eates sur les plaintes<\/td>\n\t\t\t<td>Nouvelle responsabilit\u00e9 essentielle<\/td>\n\t\t\t<td>Nouveau cadre minist\u00e9riel des r\u00e9sultats<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<th rowspan=\"2\" scope=\"row\" class=\"active text-center\">Programmes<\/th>\n\t\t\t<td>Examen des activit\u00e9s du SCRS<\/td>\n\t\t\t<td rowspan=\"2\">Examens des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement, et enqu\u00eates sur les plaintes<\/td>\n\t\t\t<td rowspan=\"2\">Nouveau programme<\/td>\n\t\t\t<td rowspan=\"2\">Nouveau cadre minist\u00e9riel des r\u00e9sultats<\/td>\n\t\t<\/tr>\n\t\t<tr>\n\t\t\t<td>Enqu\u00eates sur les plaintes contre le SCRS&nbsp;<abbr style=\"border-bottom: none; text-decoration-line: none; text-decoration-style: initial;\" title=\"Service canadien du renseignement de s\u00e9curit\u00e9\">SCRS<\/abbr><\/td>\n\t\t<\/tr>\n\t<\/tbody>\n<\/table>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"section_5_4\">Renseignements connexes sur le R\u00e9pertoire des programmes<\/h3>\n\n\n\n<p>Des renseignements sur les d\u00e9penses pr\u00e9vues, les ressources humaines et les r\u00e9sultats li\u00e9s au\nr\u00e9pertoire des programmes de l\u2019OSSNR sont accessibles dans&nbsp;<a href=\"https:\/\/www.tbs-sct.gc.ca\/ems-sgd\/edb-bdd\/index-fra.html\" target=\"_blank\" rel=\"noreferrer noopener\">l\u2019InfoBase du GC.<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"section_5_5\">Tableaux de renseignements suppl\u00e9mentaires<\/h3>\n\n\n\n<p class=\" translation-block\"><p>Les tableaux de renseignements suppl\u00e9mentaires ci-dessous sont accessibles sur le <a href=\"https:\/\/nsira-ossnr.gc.ca\/fr\/\">site Web de l\u2019OSSNR<\/a>:<\/p><\/p>\n\n\n\n<ul>\n<li>Analyse comparative entre les sexes Plus<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"section_5_6\">D\u00e9penses fiscales f\u00e9d\u00e9rales<\/h3>\n\n\n\n<p>Le plan minist\u00e9riel de l\u2019OSSNR ne comprend pas de renseignements sur les d\u00e9penses fiscales.<\/p>\n\n\n\n<p class=\" translation-block\"><p>Les mesures fiscales rel\u00e8vent du ministre des Finances. Le minist\u00e8re des Finances Canada publie chaque ann\u00e9e des estimations et des projections du co\u00fbt des d\u00e9penses fiscales f\u00e9d\u00e9rale dans le <a href=\"https:\/\/www.canada.ca\/fr\/ministere-finances\/services\/publications\/depenses-fiscales\/2020\/partie-1.html\" target=\"_blank\" rel=\"noopener\">Rapport sur les d\u00e9pense fiscales f\u00e9d\u00e9rales<\/a>. Ce rapport fournit aussi des renseignements g\u00e9n\u00e9raux d\u00e9taill\u00e9s sur les d\u00e9penses fiscales, y compris les objectifs, les renseignements historiques et les renvois aux programmes des d\u00e9penses f\u00e9d\u00e9raux connexes, ainsi que sur les \u00e9valuations fiscales, les rapports de recherche et les analyses comparatives entre les sexes plus.<\/p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"section_5_7\">Coordonn\u00e9es de l\u2019organisation<\/h3>\n\n\n\n<p>Office de surveillance des activit\u00e9s en mati\u00e8re de s\u00e9curit\u00e9 nationale et de renseignement<br>C.P. 2430, succursale \u00ab D \u00bb Ottawa, Ontario<br>K1P&nbsp;5W5<\/p>\n\n\n\n<p><strong>Num\u00e9ro(s) de t\u00e9l\u00e9phone :<\/strong>&nbsp;Le num\u00e9ro de t\u00e9l\u00e9phone est temporairement d\u00e9sactiv\u00e9.<br><strong>T\u00e9l\u00e9copieur<\/strong>: Le num\u00e9ro de t\u00e9l\u00e9copieur est temporairement d\u00e9sactiv\u00e9.<br><strong>Courriel<\/strong>: <a href=\"mailto:info@nsira-ossnr.gc.ca\">info@nsira-ossnr.gc.ca<\/a><br><strong>Website<\/strong>: <a href=\"http:\/\/www.nsira-ossnr.gc.ca\/fr\/\">www.nsira-ossnr.gc.ca\/fr\/<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"30-appendix-definitions\">Annexe : d\u00e9finitions<\/h2>\n\n\n\n<p class=\" translation-block\"><strong>cr\u00e9dit<\/strong>\u00a0<em>(appropriation)<\/em><\/p>\n\n\n\n<p>Autorisation donn\u00e9e par le Parlement d\u2019effectuer des paiements sur le Tr\u00e9sor.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>d\u00e9penses budg\u00e9taires<\/strong> \u00a0<em>(budgetary expenditures)<\/em><\/p>\n\n\n\n<p>D\u00e9penses de fonctionnement et en capital; paiements de transfert \u00e0 d\u2019autres ordres de gouvernement, \u00e0 des minist\u00e8res ou \u00e0 des particuliers; et paiements \u00e0 des soci\u00e9t\u00e9s d\u2019\u00c9tat.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>responsabilit\u00e9 essentielle<\/strong>\u00a0<em>(core responsibility)<\/em><\/p>\n\n\n\n<p>Fonction ou r\u00f4le permanent exerc\u00e9 par un minist\u00e8re. Les intentions du minist\u00e8re concernant une responsabilit\u00e9 essentielle se traduisent par un ou plusieurs r\u00e9sultats minist\u00e9riels auxquels le minist\u00e8re cherche \u00e0 contribuer ou sur lesquels il veut avoir une influence.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>plan minist\u00e9riel<\/strong>\u00a0<em>(Departmental Plan)<\/em><\/p>\n\n\n\n<p>Expos\u00e9 des choix strat\u00e9giques qui montre comment un minist\u00e8re entend r\u00e9aliser ses priorit\u00e9s et obtenir les r\u00e9sultats connexes. De fa\u00e7on g\u00e9n\u00e9rale, un plan explique la logique qui sous-tend les strat\u00e9gies retenues et tend \u00e0 mettre l\u2019accent sur des mesures qui se traduisent par des r\u00e9sultats attendus.<\/p>\n\n\n\n<p><strong>departmental priority<\/strong>&nbsp;<em>(priorit\u00e9)<\/em><\/p>\n\n\n\n<p>Plan ou projet qu\u2019un minist\u00e8re a choisi de cibler et dont il rendra compte au cours de la p\u00e9riode de planification. Il s\u2019agit de ce qui importe le plus ou qui doit \u00eatre fait en premier pour appuyer la r\u00e9alisation des r\u00e9sultats minist\u00e9riels souhait\u00e9s.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>r\u00e9sultat minist\u00e9riel<\/strong>\u00a0<em>(departmental result)<\/em><\/p>\n\n\n\n<p>Effet ou r\u00e9sultat que vise un minist\u00e8re. Un r\u00e9sultat minist\u00e9riel \u00e9chappe g\u00e9n\u00e9ralement au contr\u00f4le direct des minist\u00e8res, mais il devrait \u00eatre influenc\u00e9 par les r\u00e9sultats des programmes.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>indicateur de r\u00e9sultat minist\u00e9riel\u00a0<\/strong><em>(departmental result indicator)<\/em><\/p>\n\n\n\n<p>Mesure quantitative des progr\u00e8s r\u00e9alis\u00e9s par rapport \u00e0 un r\u00e9sultat minist\u00e9riel.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>cadre minist\u00e9riel des r\u00e9sultats<\/strong>\u00a0<em>(departmental results framework)<\/em><\/p>\n\n\n\n<p>Cadre qui \u00e9tablit un lien entre les responsabilit\u00e9s essentielles et les r\u00e9sultats minist\u00e9riels ainsi que les indicateurs de r\u00e9sultat minist\u00e9riel d\u2019un minist\u00e8re.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>rapport sur les r\u00e9sultats minist\u00e9riels<\/strong>\u00a0<em>(Departmental Results Report)<\/em><\/p>\n\n\n\n<p>Rapport qui pr\u00e9sente les r\u00e9alisations r\u00e9elles d\u2019un minist\u00e8re par rapport aux plans, aux priorit\u00e9s et aux r\u00e9sultats attendus \u00e9nonc\u00e9s dans le Plan minist\u00e9riel correspondant.<\/p>\n\n\n\n<p><strong>experimentation<\/strong>&nbsp;<em>(exp\u00e9rimentation)<\/em><\/p>\n\n\n\n<p>La tenue d\u2019activit\u00e9s visant \u00e0 \u00e9tudier, \u00e0 mettre \u00e0 l\u2019essai et \u00e0 comparer les effets et les r\u00e9percussions de politiques et d\u2019interventions afin d\u2019\u00e9tayer la prise de d\u00e9cisions fond\u00e9e sur des \u00e9l\u00e9ments probants, et \u00e0 am\u00e9liorer les r\u00e9sultats pour les Canadiens en apprenant ce qui fonctionne, pour qui et dans quelles circonstances. L\u2019exp\u00e9rimentation est li\u00e9e \u00e0 l\u2019innovation (l\u2019essai de nouvelles approches), mais en est diff\u00e9rente, car elle comporte une comparaison rigoureuse des r\u00e9sultats. \u00c0 titre d\u2019exemple, le fait d\u2019utiliser un nouveau site Web pour communiquer avec les Canadiens peut \u00eatre un cas d\u2019innovation; le fait de conduire des essais syst\u00e9matiques du nouveau site Web par rapport aux outils existants de sensibilisation ou un ancien site Web pour voir celui qui permet une mobilisation plus efficace est une exp\u00e9rimentation.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>\u00e9quivalent temps plein<\/strong>\u00a0<em>(full\u2011time equivalent)<\/em><\/p>\n\n\n\n<p>Mesure utilis\u00e9e pour repr\u00e9senter une ann\u00e9e-personne compl\u00e8te d\u2019un employ\u00e9 dans le budget minist\u00e9riel. Pour un poste donn\u00e9, le nombre d\u2019\u00e9quivalents temps plein repr\u00e9sente le rapport entre le nombre d\u2019heures travaill\u00e9es par une personne, divis\u00e9 par le nombre d\u2019heures normales pr\u00e9vues dans sa convention collective.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>analyse comparative entre les sexes plus [ACS Plus]<\/strong>\u00a0<em>(gender-based analysis plus (GBA Plus))<\/em><\/p>\n\n\n\n<p>Est un outil analytique servant \u00e0 l\u2019\u00e9laboration de politiques, de programmes et d\u2019autres initiatives adapt\u00e9s et inclusifs. Il s\u2019agit d\u2019un processus permettant de comprendre qui est impact\u00e9 par l\u2019enjeu ou l\u2019occasion abord\u00e9e par l\u2019initiative; de d\u00e9terminer comment l\u2019initiative pourrait \u00eatre adapt\u00e9e aux diff\u00e9rents besoins des personnes les plus impact\u00e9es; de m\u00eame que d\u2019anticiper et de lever les obstacles emp\u00eachant d\u2019acc\u00e9der \u00e0 l\u2019initiative ou d\u2019en b\u00e9n\u00e9ficier. L\u2019ACS Plus est une analyse intersectionnelle qui va au-del\u00e0 des diff\u00e9rences biologiques (sexe) et socioculturelles (genre), pour prendre en compte d\u2019autres facteurs tels que l\u2019\u00e2ge, le handicap, l\u2019\u00e9ducation, l\u2019ethnicit\u00e9, la situation \u00e9conomique, la g\u00e9ographie (y compris la ruralit\u00e9), la langue, la race, la religion et l\u2019orientation sexuelle.<\/p>\n\n\n\n<p><strong>government-wide priorities<\/strong>&nbsp;<em>(priorit\u00e9s pangouvernementales)<\/em><\/p>\n\n\n\n<p>For the purpose of the 2020\u201321 Departmental Results Report, those high-level themes outlining the government\u2019s agenda in the 2019 Speech from the Throne, namely: Fighting climate change; Strengthening the Middle Class; Walking the road of reconciliation; Keeping Canadians safe and healthy; and Positioning Canada for success in an uncertain world.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>initiative horizontale<\/strong>\u00a0<em>(horizontal initiative)<\/em><\/p>\n\n\n\n<p>Initiative dans le cadre de laquelle deux organisations f\u00e9d\u00e9rales ou plus re\u00e7oivent du financement dans le but d\u2019atteindre un r\u00e9sultat commun, souvent associ\u00e9 \u00e0 une priorit\u00e9 du gouvernement.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>d\u00e9penses non budg\u00e9taires<\/strong>\u00a0<em>(non\u2011budgetary expenditures)<\/em><\/p>\n\n\n\n<p>Autorisations non budg\u00e9taires comprenant des op\u00e9rations sur l\u2019actif et le passif pour des pr\u00eats, des placements et des avances ou des comptes \u00e0 fins d\u00e9termin\u00e9es, \u00e9tablis en vertu de lois particuli\u00e8res ou d\u2019autorisations non l\u00e9gislatives dans le budget des d\u00e9penses et ailleurs. Les op\u00e9rations non budg\u00e9taires sont des d\u00e9penses et des rentr\u00e9es li\u00e9es aux cr\u00e9ances du gouvernement envers des tiers et \u00e0 ses obligations \u00e0 l\u2019\u00e9gard de ces derniers. Les op\u00e9rations non budg\u00e9taires incluent l\u2019ensemble des op\u00e9rations portant sur les pr\u00eats, les investissements et les avances de fonds; en comptant et en comptes d\u00e9biteurs; en fonds publics re\u00e7us ou per\u00e7us \u00e0 des fins admises; et tout autre actif et responsabilit\u00e9. Les autres biens ou obligations, qui ne sont pas d\u00e9finis de fa\u00e7on pr\u00e9cise dans les codes d\u2019autorisations\u202fG \u00e0 P, doivent \u00eatre enregistr\u00e9s sous un code\u202fR, qui est le code d\u2019autorisation r\u00e9siduel pour tous les autres biens et obligations.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>rendement<\/strong> <em>(performance\u00a0)<\/em><\/p>\n\n\n\n<p>Utilisation qu\u2019une organisation a faite de ses ressources en vue d\u2019obtenir ses r\u00e9sultats, mesure dans laquelle ces r\u00e9sultats se comparent \u00e0 ceux que l\u2019organisation souhaitait obtenir, et mesure dans laquelle les le\u00e7ons apprises ont \u00e9t\u00e9 cern\u00e9es.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>indicateur de rendement<\/strong>\u00a0<em>(performance indicator)<\/em><\/p>\n\n\n\n<p>Moyen qualitatif ou quantitatif de mesurer un extrant ou un r\u00e9sultat en vue de d\u00e9terminer le rendement d\u2019un minist\u00e8re, d\u2019un programme, d\u2019une politique ou d\u2019une initiative par rapport aux r\u00e9sultats attendus.<\/p>\n\n\n\n<p><strong>performance reporting<\/strong>&nbsp;<em>(production de rapports sur le rendement)<\/em><\/p>\n\n\n\n<p>Processus de communication d\u2019information sur le rendement fond\u00e9e sur des \u00e9l\u00e9ments probants. La production de rapports sur le rendement appuie la prise de d\u00e9cisions, la responsabilisation et la transparence.<\/p>\n\n\n\n<p><strong>plan<\/strong>&nbsp;<em>(plan)<\/em><\/p>\n\n\n\n<p>Expos\u00e9 des choix strat\u00e9giques qui montre comment une organisation entend r\u00e9aliser ses priorit\u00e9s et obtenir les r\u00e9sultats connexes. De fa\u00e7on g\u00e9n\u00e9rale, un plan explique la logique qui sous-tend les strat\u00e9gies retenues et tend \u00e0 mettre l\u2019accent sur des mesures qui se traduisent par des r\u00e9sultats attendus.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>d\u00e9penses pr\u00e9vues<\/strong>\u00a0<em>(planned spending)<\/em><\/p>\n\n\n\n<p>En ce qui a trait au Plan minist\u00e9riel et au Rapport sur les r\u00e9sultats minist\u00e9riels, montants pr\u00e9sent\u00e9s dans le Budget principal des d\u00e9penses.<\/p>\n\n\n\n<p>Un minist\u00e8re est cens\u00e9 \u00eatre au courant des autorisations qu\u2019il a demand\u00e9es et obtenues. La d\u00e9termination des d\u00e9penses pr\u00e9vues rel\u00e8ve du minist\u00e8re, et ce dernier doit \u00eatre en mesure de justifier les d\u00e9penses et les augmentations pr\u00e9sent\u00e9es dans son Plan minist\u00e9riel et son Rapport sur les r\u00e9sultats minist\u00e9riels.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>programme<\/strong>\u00a0<em>(program)<\/em><\/p>\n\n\n\n<p>Services et activit\u00e9s, pris s\u00e9par\u00e9ment ou en groupe, ou une combinaison des deux, qui sont g\u00e9r\u00e9s\nensemble au sein d\u2019un minist\u00e8re et qui portent sur un ensemble d\u00e9termin\u00e9 d\u2019extrants, de r\u00e9sultats ou\nde niveaux de services.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>r\u00e9pertoire des programmes<\/strong>\u00a0<em>(program inventory)<\/em><\/p>\n\n\n\n<p>Compilation de l\u2019ensemble des programmes du minist\u00e8re qui d\u00e9crit la mani\u00e8re dont les ressources sont organis\u00e9es pour s\u2019acquitter des responsabilit\u00e9s essentielles du minist\u00e8re et atteindre ses r\u00e9sultats pr\u00e9vus.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>r\u00e9sultat<\/strong>\u00a0<em>(result)<\/em><\/p>\n\n\n\n<p>Cons\u00e9quence attribuable en partie aux activit\u00e9s d\u2019un minist\u00e8re, d\u2019une politique, d\u2019un programme ou d\u2019une initiative. Les r\u00e9sultats ne rel\u00e8vent pas d\u2019un minist\u00e8re, d\u2019une politique, d\u2019un programme ou d\u2019une initiative unique, mais ils s\u2019inscrivent dans la sph\u00e8re d\u2019influence du minist\u00e8re.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>d\u00e9penses l\u00e9gislatives<\/strong>\u00a0<em>(statutory expenditures)<\/em><\/p>\n\n\n\n<p>D\u00e9penses approuv\u00e9es par le Parlement \u00e0 la suite de l\u2019adoption d\u2019une loi autre qu\u2019une loi de cr\u00e9dits. La loi pr\u00e9cise les fins auxquelles peuvent servir les d\u00e9penses et les conditions dans lesquelles elles peuvent \u00eatre effectu\u00e9es.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>cible<\/strong> <em>(target\u00a0)<\/em><\/p>\n\n\n\n<p>Niveau mesurable du rendement ou du succ\u00e8s qu\u2019un minist\u00e8re, un programme ou une initiative pr\u00e9voit atteindre dans un d\u00e9lai pr\u00e9cis. Une cible peut \u00eatre quantitative ou qualitative.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>d\u00e9penses vot\u00e9es<\/strong>\u00a0<em>(voted expenditures)<\/em><\/p>\n\n\n\n<p>D\u00e9penses approuv\u00e9es annuellement par le Parlement par une loi de cr\u00e9dits. Le libell\u00e9 de chaque cr\u00e9dit \u00e9nonce les conditions selon lesquelles les d\u00e9penses peuvent \u00eatre effectu\u00e9es.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Compte rendu soulignant les r\u00e9sultats, les risques et les changements importants quant au fonctionnement, au personnel et aux programmes<\/p>","protected":false},"author":1,"featured_media":2712,"parent":3093,"menu_order":44,"comment_status":"closed","ping_status":"closed","template":"template-nsira-subpages.php","meta":{"inline_featured_image":false},"categories":[9,10,42,13,28],"tags":[185],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Departmental Plan: 2022-2023 - National Security and Intelligence Review Agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nsira-ossnr.gc.ca\/fr\/secretariat\/operations-du-secretariat\/departmental-plan-2022-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Departmental Plan: 2022-2023 - National Security and Intelligence Review Agency\" \/>\n<meta property=\"og:description\" content=\"Statement outlining results, risks and significant changes in operations, personnel and programs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nsira-ossnr.gc.ca\/fr\/secretariat\/operations-du-secretariat\/departmental-plan-2022-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"National Security and Intelligence Review Agency\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T20:50:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/Reports-Featured.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"23 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/\",\"url\":\"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/\",\"name\":\"Departmental Plan: 2022-2023 - National Security and Intelligence Review Agency\",\"isPartOf\":{\"@id\":\"https:\/\/nsira-ossnr.gc.ca\/#website\"},\"datePublished\":\"2023-02-27T18:39:57+00:00\",\"dateModified\":\"2026-02-02T20:50:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Secretariat\",\"item\":\"\/secretariat\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secretariat Operations\",\"item\":\"\/secretariat\/secretariat-operations\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Departmental Plan: 2022-2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nsira-ossnr.gc.ca\/#website\",\"url\":\"https:\/\/nsira-ossnr.gc.ca\/\",\"name\":\"National Security and Intelligence Review Agency\",\"description\":\"Official Website\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nsira-ossnr.gc.ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Departmental Plan: 2022-2023 - National Security and Intelligence Review Agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nsira-ossnr.gc.ca\/fr\/secretariat\/operations-du-secretariat\/departmental-plan-2022-2023\/","og_locale":"fr_CA","og_type":"article","og_title":"Departmental Plan: 2022-2023 - National Security and Intelligence Review Agency","og_description":"Statement outlining results, risks and significant changes in operations, personnel and programs","og_url":"https:\/\/nsira-ossnr.gc.ca\/fr\/secretariat\/operations-du-secretariat\/departmental-plan-2022-2023\/","og_site_name":"National Security and Intelligence Review Agency","article_modified_time":"2026-02-02T20:50:42+00:00","og_image":[{"width":350,"height":500,"url":"https:\/\/nsira-ossnr.gc.ca\/wp-content\/uploads\/Reports-Featured.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"23 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/","url":"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/","name":"Departmental Plan: 2022-2023 - National Security and Intelligence Review Agency","isPartOf":{"@id":"https:\/\/nsira-ossnr.gc.ca\/#website"},"datePublished":"2023-02-27T18:39:57+00:00","dateModified":"2026-02-02T20:50:42+00:00","breadcrumb":{"@id":"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nsira-ossnr.gc.ca\/secretariat\/secretariat-operations\/departmental-plan-2022-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Secretariat","item":"\/secretariat\/"},{"@type":"ListItem","position":2,"name":"Secretariat Operations","item":"\/secretariat\/secretariat-operations\/"},{"@type":"ListItem","position":3,"name":"Departmental Plan: 2022-2023"}]},{"@type":"WebSite","@id":"https:\/\/nsira-ossnr.gc.ca\/#website","url":"https:\/\/nsira-ossnr.gc.ca\/","name":"National Security and Intelligence Review Agency","description":"Official Website","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nsira-ossnr.gc.ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages\/3692"}],"collection":[{"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/comments?post=3692"}],"version-history":[{"count":14,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages\/3692\/revisions"}],"predecessor-version":[{"id":4823,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages\/3692\/revisions\/4823"}],"up":[{"embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/pages\/3093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/media\/2712"}],"wp:attachment":[{"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/media?parent=3692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/categories?post=3692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nsira-ossnr.gc.ca\/fr\/wp-json\/wp\/v2\/tags?post=3692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}